{"id":67641,"date":"2026-02-18T10:11:32","date_gmt":"2026-02-18T16:11:32","guid":{"rendered":"https:\/\/saluddigital.com\/?p=67641"},"modified":"2026-02-18T10:20:37","modified_gmt":"2026-02-18T16:20:37","slug":"imss-modernizara-12-de-36-oncocrean-con-medicina-de-precision-en-2026","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/noticias\/imss-modernizara-12-de-36-oncocrean-con-medicina-de-precision-en-2026\/","title":{"rendered":"IMSS modernizar\u00e1 12 de 36 ONCOCREAN con medicina de precisi\u00f3n en 2026"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"67641\" class=\"elementor elementor-67641\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f6815c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1f6815c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c1b1476\" data-id=\"6c1b1476\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74f100ce elementor-widget elementor-widget-heading\" data-id=\"74f100ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Las terapias dirigidas se aplicar\u00e1n en centros seleccionados del pa\u00eds y buscan atender casos espec\u00edficos con menores efectos secundarios.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c6bed6b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4c6bed6b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-630ac277\" data-id=\"630ac277\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c4644 elementor-widget elementor-widget-text-editor\" data-id=\"5c4644\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Instituto Mexicano del Seguro Social (IMSS) anunci\u00f3 que en 2026 pondr\u00e1 en operaci\u00f3n 12 Centros de Referencia Estatal para la Atenci\u00f3n del Ni\u00f1o y de la Ni\u00f1a con C\u00e1ncer (ONCOCREAN), con <strong>enfoque en medicina de precisi\u00f3n<\/strong> para tratamientos dirigidos contra el c\u00e1ncer. El anuncio se da en el marco del D\u00eda Internacional del C\u00e1ncer Infantil, que se conmemora el 15 de febrero. Como parte de la estrategia integral para la atenci\u00f3n pedi\u00e1trica oncol\u00f3gica, el <strong>IMSS incorporar\u00e1 terapias basadas en mol\u00e9culas espec\u00edficas que act\u00faan sobre determinadas caracter\u00edsticas de las c\u00e9lulas tumorales<\/strong>.<\/p><p>El titular de la Coordinaci\u00f3n de Oncolog\u00eda, Donaci\u00f3n y Trasplantes, el Dr. Enrique L\u00f3pez Aguilar, explic\u00f3 que se trata de terapias con mol\u00e9culas que permiten, en casos muy particulares, atender la patolog\u00eda con m\u00ednimos efectos secundarios y m\u00e1ximos \u00edndices de curaci\u00f3n.<\/p><p>De los <strong>36 ONCOCREAN con los que cuenta el IMSS en todo el pa\u00eds, 12 fueron seleccionados para esta primera etapa con base en el volumen de pacientes que atienden<\/strong>, el nivel de capacitaci\u00f3n del personal y la infraestructura disponible. Las terapias de medicina de precisi\u00f3n se aplicar\u00e1n en el Hospital Regional XIV Septiembre de Tuxtla Guti\u00e9rrez, Chiapas; la Unidad M\u00e9dica de Alta Especialidad Hospital General del Centro M\u00e9dico Nacional La Raza; el Hospital General Regional No. 1 \u201cDr. Carlos MacGregor S\u00e1nchez Navarro\u201d; el Hospital General Regional No. 251 en Metepec, Estado de M\u00e9xico; la UMAE Hospital de Pediatr\u00eda del CMN de Occidente en Guadalajara, Jalisco; y el Hospital General Regional No. 1 en Ciudad Obreg\u00f3n, Sonora.<\/p><p>Tambi\u00e9n estar\u00e1n disponibles en la UMAE Hospital de Especialidades No. 14 en Veracruz; la UMAE Hospital de Especialidades del CMN de M\u00e9rida, Yucat\u00e1n; la UMAE Hospital de Especialidades No. 25 de Monterrey, Nuevo Le\u00f3n; la UMAE Hospital de Gineco Pediatr\u00eda No. 48 del CMN del Baj\u00edo, Guanajuato; el Hospital General Regional No. 1 de Tijuana, Baja California; y la UMAE Hospital de Pediatr\u00eda del CMN Siglo XXI.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6507b51c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6507b51c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42bdd390\" data-id=\"42bdd390\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dd1559d elementor-widget elementor-widget-image\" data-id=\"2dd1559d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2026\/02\/02-26-25.jpg\" class=\"attachment-full size-full wp-image-67643\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a1d9e39 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4a1d9e39\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc379fa\" data-id=\"fc379fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e088ceb elementor-widget elementor-widget-text-editor\" data-id=\"6e088ceb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Dr. L\u00f3pez Aguilar detall\u00f3 que en estas unidades se busca que la medicina de precisi\u00f3n tenga mayor impacto con base en investigaci\u00f3n. En este sentido, explic\u00f3 que las c\u00e9lulas cancerosas expresan biomarcadores espec\u00edficos, por lo que \u201chay una terapia dirigida que ataca a esa c\u00e9lula cancerosa y la destruye, sin necesidad de destruir a otras. Y las terapias dirigidas justamente lo que hacen es ir nada m\u00e1s directo a las c\u00e9lulas cancerosas\u201d.<\/p><p>En esta primera fase, el plan para 2026 es iniciar los trabajos en estos 12 ONCOCREAN con medicina subespecializada, con la intenci\u00f3n de extender el modelo progresivamente a los 36 centros.<\/p><p>Desde su creaci\u00f3n, los ONCOCREAN tienen como objetivo acercar la medicina de especialidad a pacientes en todas las entidades federativas, homologar tratamientos y dar seguimiento semanal a cada caso. Actualmente, el IMSS brinda atenci\u00f3n a 5 mil 200 menores con c\u00e1ncer en estos centros.<\/p><p>Finalmente el Dr. L\u00f3pez Aguilar hizo un llamado a madres y padres de familia para estar atentos a s\u00edntomas como dolor de cabeza persistente, despertares nocturnos, v\u00f3mito sin causa aparente, p\u00e9rdida de peso, cambios de conducta o decaimiento, y acudir a las Unidades de Medicina Familiar del IMSS para valoraci\u00f3n. \u201cEs muy importante que cuando los pap\u00e1s vean que su hijo no se compone con la primera consulta, tiene alguna sintomatolog\u00eda y no se corrige, insistir hasta que est\u00e9 el diagn\u00f3stico oportuno\u201d, coment\u00f3.<\/p><p>Cabe destacar que cuando un menor acude a su cl\u00ednica familiar de primer contacto y se detectan signos o s\u00edntomas compatibles con c\u00e1ncer, se activa el protocolo correspondiente para referirlo a uno de los ONCOCREAN del pa\u00eds, esto con el fin de agilizar la atenci\u00f3n especializada.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76163d93 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"76163d93\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-226744ae\" data-id=\"226744ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d08dd91 elementor-widget elementor-widget-toggle\" data-id=\"6d08dd91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1821\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1821\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1821\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1821\"><p><strong>IMSS<\/strong><\/p><p><a href=\"https:\/\/www.imss.gob.mx\/prensa\/archivo\/202602\/081\">https:\/\/www.imss.gob.mx\/prensa\/archivo\/202602\/081<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>IMSS modernizar\u00e1 12 de 36 ONCOCREAN con medicina de precisi\u00f3n en 2026 para atender de manera oportuna a menores con c\u00e1ncer.<\/p>","protected":false},"author":1,"featured_media":67643,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160,3396],"tags":[145],"class_list":["post-67641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-uso-de-plataformas-digitales","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/67641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=67641"}],"version-history":[{"count":5,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/67641\/revisions"}],"predecessor-version":[{"id":67648,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/67641\/revisions\/67648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/67643"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=67641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=67641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=67641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}