{"id":66695,"date":"2026-01-15T09:20:26","date_gmt":"2026-01-15T15:20:26","guid":{"rendered":"https:\/\/saluddigital.com\/?p=66695"},"modified":"2026-01-15T09:23:54","modified_gmt":"2026-01-15T15:23:54","slug":"crisis-vaccinationplanner-nueva-herramienta-que-ayuda-a-decidir-que-vacunas-priorizar-en-crisis-humanitarias","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/big-data\/crisis-vaccinationplanner-nueva-herramienta-que-ayuda-a-decidir-que-vacunas-priorizar-en-crisis-humanitarias\/","title":{"rendered":"Crisis VaccinationPlanner, nueva herramienta que ayuda a decidir qu\u00e9 vacunas priorizar en crisis humanitarias"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"66695\" class=\"elementor elementor-66695\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3284ba9f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3284ba9f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48aa8701\" data-id=\"48aa8701\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fe0499c elementor-widget elementor-widget-heading\" data-id=\"4fe0499c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Investigadores del Jameel Institute y la London School of Hygiene and Tropical Medicine desarrollan un modelo que apoya la toma de decisiones en emergencias sanitarias.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ae2c31f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2ae2c31f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71f3fab4\" data-id=\"71f3fab4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f58b99e elementor-widget elementor-widget-text-editor\" data-id=\"2f58b99e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En contextos de crisis humanitaria, como guerras, desplazamientos forzados o desastres naturales, los sistemas de salud suelen colapsar r\u00e1pidamente. Una de las primeras consecuencias es la interrupci\u00f3n de los programas de vacunaci\u00f3n, lo que deja a miles de personas expuestas a enfermedades prevenibles como el sarampi\u00f3n, la difteria o la tosferina. Frente a este desaf\u00edo, investigadores del <strong>Jameel Institute del Imperial College London<\/strong> y de la <strong>London School of Hygiene and Tropical Medicine (LSHTM)<\/strong> han desarrollado una nueva herramienta para apoyar la toma de decisiones sobre vacunaci\u00f3n en escenarios de emergencia.<\/p><p>Se trata del <strong>Jameel Institute Crisis Vaccination Planner<\/strong>, un sistema de apoyo basado en modelos epidemiol\u00f3gicos y an\u00e1lisis de datos en tiempo real. Su objetivo es ayudar a organizaciones humanitarias a responder una de las preguntas m\u00e1s dif\u00edciles en una crisis: <strong>qu\u00e9 enfermedades representan el mayor riesgo inmediato y qu\u00e9 campa\u00f1as de vacunaci\u00f3n pueden salvar m\u00e1s vidas en el menor tiempo posible<\/strong>.<\/p><p>La herramienta forma parte del proyecto Jameel Institute\u2013Realtime Intelligent Support for Emergencies (RISE), una iniciativa que integra datos en tiempo real, an\u00e1lisis de brotes y modelos predictivos para apoyar a actores clave como la Organizaci\u00f3n Mundial de la Salud (OMS), M\u00e9dicos Sin Fronteras (MSF) y la Oficina de Coordinaci\u00f3n de Asuntos Humanitarios de la ONU (OCHA). La idea central es hacer que m\u00e9todos anal\u00edticos complejos sean m\u00e1s accesibles para quienes trabajan directamente en el terreno.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-630ee4a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"630ee4a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3ac98af4\" data-id=\"3ac98af4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32e061d5 elementor-widget elementor-widget-image\" data-id=\"32e061d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2026\/01\/01-26-19.jpg\" class=\"attachment-full size-full wp-image-66697\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-778dc49\" data-id=\"778dc49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c5ce132 elementor-widget elementor-widget-text-editor\" data-id=\"5c5ce132\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A diferencia de otros sistemas que buscan predecir con exactitud c\u00f3mo evolucionar\u00e1 un brote, el <strong>Crisis Vaccination Planner<\/strong> se enfoca en algo distinto, ya que plantea identificar qu\u00e9 informaci\u00f3n falta y c\u00f3mo mejorar la planificaci\u00f3n futura. Para ello, combina datos sobre la cobertura de vacunaci\u00f3n antes de la crisis, la composici\u00f3n demogr\u00e1fica de la poblaci\u00f3n y el grado de interrupci\u00f3n de los servicios de salud. Con estos elementos, ayuda a proyectar el riesgo de brotes y a priorizar intervenciones que puedan <strong>reducir el tama\u00f1o de los brotes, retrasar su propagaci\u00f3n y optimizar el uso de recursos limitados<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-221d352a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"221d352a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec5bc88\" data-id=\"ec5bc88\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2571d726 elementor-widget elementor-widget-text-editor\" data-id=\"2571d726\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El equipo de investigaci\u00f3n ya comenz\u00f3 a aplicar la herramienta en un caso real, utilizando datos del conflicto en <strong>Gaza, Palestina<\/strong>. El objetivo es analizar c\u00f3mo distintos niveles de interrupci\u00f3n en la vacunaci\u00f3n podr\u00edan influir en la magnitud y el momento de posibles brotes, y as\u00ed ofrecer insumos que apoyen la toma de decisiones en una situaci\u00f3n de extrema complejidad.<\/p><p>Por su parte, la Dra. Bhargavi Rao, col\u00edder del proyecto RISE y profesora asociada cl\u00ednica en la LSHTM, crisis como las de Gaza o Tigray muestran lo r\u00e1pido que pueden colapsar los sistemas de salud y la importancia de usar datos para guiar la acci\u00f3n. \u201cEl Crisis Vaccination Planner en situaciones de crisis nos ayuda a convertir la incertidumbre en informaci\u00f3n valiosa, lo que permite a los actores humanitarios tomar decisiones m\u00e1s r\u00e1pidas y basadas en datos que pueden salvar vidas\u201d, detall\u00f3.<\/p><p>Por su parte, el Dr. Oliver Watson, tambi\u00e9n col\u00edder del proyecto y profesor en Imperial College London, explic\u00f3 que: \u201cNuestro objetivo es hacer que el modelado complejo sea accesible y operativo. El JICVP es un punto de partida para ese debate. Al comprender los l\u00edmites de los datos y m\u00e9todos actuales, podemos trabajar con nuestros socios para dise\u00f1ar la pr\u00f3xima generaci\u00f3n de herramientas que realmente ayuden a los equipos de respuesta sobre el terreno\u201d.<\/p><p>Actualmente, el proyecto se encuentra en una fase piloto de codise\u00f1o, en la que investigadores y organizaciones humanitarias trabajan juntos para asegurar que la herramienta responda a las necesidades reales de campo. En esta etapa participan activamente instituciones como la OMS, MSF y OCHA, que aportan su experiencia directa en crisis sanitarias.<\/p><p>A futuro, el equipo planea incorporar m\u00e9tricas sobre la calidad de la vigilancia epidemiol\u00f3gica, lo que permitir\u00e1 evaluar c\u00f3mo la capacidad de detecci\u00f3n influye en la respuesta a los brotes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b3263ad elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3b3263ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-368ea2bf\" data-id=\"368ea2bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cc482fa elementor-widget elementor-widget-toggle\" data-id=\"1cc482fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4821\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-4821\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-4821\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-4821\"><p><strong>IMPERIAL COLLEGE LONDON<\/strong><\/p><p><a href=\"https:\/\/www.imperial.ac.uk\/news\/articles\/medicine\/school-public-health\/2025\/new-modelling-tool-unveiled-to-support-enhanced-vaccination-planning-in-humanitarian-crises\/\">https:\/\/www.imperial.ac.uk\/news\/articles\/medicine\/school-public-health\/2025\/new-modelling-tool-unveiled-to-support-enhanced-vaccination-planning-in-humanitarian-crises\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Una nueva herramienta desarrollada en Reino Unido, denominada Crisis Vaccination Planner, ayuda a decidir qu\u00e9 vacunas priorizar en crisis humanitarias.<\/p>","protected":false},"author":1,"featured_media":66697,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[156,160],"tags":[145],"class_list":["post-66695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-big-data","category-noticias","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/66695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=66695"}],"version-history":[{"count":5,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/66695\/revisions"}],"predecessor-version":[{"id":66701,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/66695\/revisions\/66701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/66697"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=66695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=66695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=66695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}