{"id":66254,"date":"2026-01-05T09:56:46","date_gmt":"2026-01-05T15:56:46","guid":{"rendered":"https:\/\/saluddigital.com\/?p=66254"},"modified":"2026-01-05T10:00:45","modified_gmt":"2026-01-05T16:00:45","slug":"universidad-de-michigan-lanza-clinica-especializada-en-interfaces-cerebro-computadora","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/big-data\/universidad-de-michigan-lanza-clinica-especializada-en-interfaces-cerebro-computadora\/","title":{"rendered":"Universidad de Michigan lanza cl\u00ednica especializada en interfaces cerebro-computadora"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"66254\" class=\"elementor elementor-66254\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16b96317 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"16b96317\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a05aa96\" data-id=\"4a05aa96\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f0b8a0e elementor-widget elementor-widget-heading\" data-id=\"2f0b8a0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La nueva cl\u00ednica evaluar\u00e1 a pacientes con lesiones neurol\u00f3gicas y facilitar\u00e1 el acceso a terapias emergentes y ensayos cl\u00ednicos con tecnolog\u00edas de comunicaci\u00f3n directa entre el cerebro y dispositivos externos.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19e67546 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"19e67546\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60b8ae02\" data-id=\"60b8ae02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68650979 elementor-widget elementor-widget-text-editor\" data-id=\"68650979\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Universidad de Michigan anunci\u00f3 la puesta en marcha de una cl\u00ednica especializada en interfaces cerebro-computadora o <em>brain-computer interfaces<\/em> (BCI), dirigida a pacientes con discapacidades motoras y del habla causadas por lesiones o enfermedades neurol\u00f3gicas. Con esta iniciativa, el sistema de salud se convierte en uno de los primeros en Estados Unidos en contar con una cl\u00ednica dedicada exclusivamente a este tipo de tecnolog\u00eda.<\/p><p>Las BCI son sistemas capaces de decodificar se\u00f1ales neuronales y traducirlas en acciones, como el control de dispositivos digitales o, potencialmente, la restauraci\u00f3n del movimiento y el habla. Estas tecnolog\u00edas buscan recuperar funciones perdidas a causa de padecimientos como accidentes cerebrovasculares, lesiones de la m\u00e9dula espinal, esclerosis lateral amiotr\u00f3fica (ELA) y atrofia muscular progresiva, entre otros.<\/p><p>La cl\u00ednica estar\u00e1 liderada por Matthew Willsey, m\u00e9dico neurocirujano e ingeniero biom\u00e9dico, quien destac\u00f3 que el desarrollo de las BCI abre nuevas posibilidades terap\u00e9uticas para personas con discapacidades severas. De acuerdo con el especialista, estas tecnolog\u00edas permiten utilizar se\u00f1ales cerebrales para restaurar funciones de comunicaci\u00f3n y movimiento, ya sea a trav\u00e9s de dispositivos digitales o, en el futuro, directamente en el cuerpo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-703591bb elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"703591bb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-556e41b5\" data-id=\"556e41b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61f833f9 elementor-widget elementor-widget-image\" data-id=\"61f833f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2026\/01\/01-26-03.jpg\" class=\"attachment-full size-full wp-image-66256\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f852e23 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"f852e23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-107a643f\" data-id=\"107a643f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68696c84 elementor-widget elementor-widget-text-editor\" data-id=\"68696c84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La BCI Clinic promover\u00e1 la colaboraci\u00f3n entre expertos en neurocirug\u00eda, neurolog\u00eda, neurorrehabilitaci\u00f3n, neurocuidados intensivos y neuroanestesia, adem\u00e1s de investigadores l\u00edderes en el desarrollo de tecnolog\u00edas BCI. Los pacientes ser\u00e1n evaluados de manera integral para determinar su elegibilidad para distintas intervenciones, incluyendo terapias ya aprobadas como la estimulaci\u00f3n del nervio vago para debilidad posterior a un accidente cerebrovascular.<\/p><p>Asimismo, los profesionales de la cl\u00ednica informar\u00e1n a los pacientes sobre oportunidades para participar en ensayos cl\u00ednicos actuales o futuros relacionados con interfaces cerebro-computadora implantables.<\/p><p>Cabe destacar que, en junio de 2025, el equipo de Willsey realiz\u00f3 el primer registro en humanos con una nueva BCI inal\u00e1mbrica, implantada de forma temporal durante una cirug\u00eda de epilepsia. La tecnolog\u00eda fue desarrollada por la empresa Paradromics.<\/p><p>Adem\u00e1s, la Universidad de Michigan participar\u00e1 como centro principal en el estudio cl\u00ednico Connect-One, que evaluar\u00e1 un dispositivo de Paradromics y que recibi\u00f3 aprobaci\u00f3n de la Administraci\u00f3n de Alimentos y Medicamentos (FDA, en ingl\u00e9s) en noviembre de 2025. En paralelo, el equipo encabeza otro ensayo cl\u00ednico enfocado en evaluar la seguridad preliminar de un dispositivo experimental dise\u00f1ado para restaurar funciones motoras y del habla.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30d4e5cf elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"30d4e5cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d55bec0\" data-id=\"3d55bec0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f998884 elementor-widget elementor-widget-toggle\" data-id=\"5f998884\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1601\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1601\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1601\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1601\"><p><strong>MICHIGAN MEDICINE<\/strong><\/p><p><a href=\"https:\/\/www.michiganmedicine.org\/news-release\/university-michigan-health-opens-brain-computer-interface-clinic-among-first-nation\">https:\/\/www.michiganmedicine.org\/news-release\/university-michigan-health-opens-brain-computer-interface-clinic-among-first-nation<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Universidad de Michigan lanza cl\u00ednica especializada en interfaces cerebro-computadora para pacientes con lesiones neurol\u00f3gicas.<\/p>","protected":false},"author":1,"featured_media":66256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[156,160],"tags":[145],"class_list":["post-66254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-big-data","category-noticias","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/66254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=66254"}],"version-history":[{"count":5,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/66254\/revisions"}],"predecessor-version":[{"id":66262,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/66254\/revisions\/66262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/66256"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=66254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=66254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=66254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}