{"id":6572,"date":"2020-02-24T12:22:24","date_gmt":"2020-02-24T18:22:24","guid":{"rendered":"https:\/\/saluddigital.com\/?p=6572"},"modified":"2025-10-21T15:34:16","modified_gmt":"2025-10-21T21:34:16","slug":"universidad-san-pablo-en-tucuman-argentina-crea-foro-para-discusion-sobre-la-salud-digital","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/avance-de-la-ciencia\/universidad-san-pablo-en-tucuman-argentina-crea-foro-para-discusion-sobre-la-salud-digital\/","title":{"rendered":"Universidad San Pablo in Tucum\u00e1n, Argentina, creates a forum for discussion on Digital Health"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"6572\" class=\"elementor elementor-6572\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c6c4c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"9c6c4c7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41d4475\" data-id=\"41d4475\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0033d2 elementor-widget elementor-widget-heading\" data-id=\"c0033d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The Tucum\u00e1n government promotes scientific knowledge with the aim of advising specialists on the use of new technologies that penetrate Digital Health and that aim to improve the quality of public health services.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dcf0c08 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"dcf0c08\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4e8a33e\" data-id=\"4e8a33e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d14db82 elementor-widget elementor-widget-text-editor\" data-id=\"d14db82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Tucum\u00e1n government \u2013province of Argentina\u2013 places importance on public policies related to the implementation of Digital Health in all its health services.<\/p><p>That is why he developed the <strong>X Technological October<\/strong>, a congress that serves as a platform and meeting point between specialists of the new Information and Communication Technologies (ICT), and doctors, with the aim of sharing experiences and knowledge.<\/p><p>The debates in which they can participate, address current issues that put the patient as a key point making it the central axis of all clinical experience and empowering it through devices and platforms that can be managed with good advice.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2aa379e\" data-id=\"2aa379e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecdf092 elementor-widget elementor-widget-image\" data-id=\"ecdf092\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"416\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2020\/02\/10-19-40-destacada_e_interna.jpg\" class=\"attachment-full size-full wp-image-6573\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2020\/02\/10-19-40-destacada_e_interna.jpg 750w, https:\/\/saluddigital.com\/wp-content\/uploads\/2020\/02\/10-19-40-destacada_e_interna-658x365.jpg 658w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68adcd0 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"68adcd0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0c64156\" data-id=\"0c64156\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14455fd elementor-widget elementor-widget-text-editor\" data-id=\"14455fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The purpose is to open roads to acquire tools and equipment that can reach the most remote areas of the region and, thus, eliminate the inequality gap in terms of access.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8fcc3a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"8fcc3a4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3b3a501\" data-id=\"3b3a501\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6acb922 elementor-widget elementor-widget-image\" data-id=\"6acb922\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"933\" height=\"535\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2020\/02\/10-19-40.jpeg\" class=\"attachment-full size-full wp-image-6575\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2020\/02\/10-19-40.jpeg 933w, https:\/\/saluddigital.com\/wp-content\/uploads\/2020\/02\/10-19-40-637x365.jpeg 637w, https:\/\/saluddigital.com\/wp-content\/uploads\/2020\/02\/10-19-40-768x440.jpeg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2020\/02\/10-19-40-840x482.jpeg 840w\" sizes=\"(max-width: 933px) 100vw, 933px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8475b45\" data-id=\"8475b45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fedcbc elementor-widget elementor-widget-text-editor\" data-id=\"4fedcbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Rossana Chahla, a member of the Argentine Ministry of Health, considered that the implications of this new digital and technological era make a good synthesis to achieve common goals and \u201cwork together, public and private, and join efforts to agree and discuss on current issues. \"<\/strong><\/p><p>In the public agenda, the sum of efforts between science and technology through interdisciplinary teams (such as medicine, biology and informatics) to develop systems based on programming and algorithms is considered.<\/p><p>The digital transformation will detect to prevent and anticipate any disease and, also, provide people with quality infrastructure so that the internet network allows to perform the work in real time.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-388d214 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"388d214\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65144ad\" data-id=\"65144ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3aac90e elementor-widget elementor-widget-text-editor\" data-id=\"3aac90e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The main focus will be to maintain the doctor-patient relationship with a link where both can participate and give their opinions to make decisions about possible solutions and can get to know each other thoroughly to establish empathy.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-576215a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"576215a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87986cf\" data-id=\"87986cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ae0a56 elementor-widget elementor-widget-toggle\" data-id=\"7ae0a56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1281\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1281\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1281\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1281\"><p><strong>GOVERNMENT OF TUCUMAN<\/strong><\/p><p><a href=\"https:\/\/comunicaciontucuman.gob.ar\/2019\/10\/la-salud-en-la-era-digital-una-agenda-obligatoria\/\">https:\/\/comunicaciontucuman.gob.ar\/2019\/10\/la-salud-en-la-era-digital-una-agenda-obligatoria\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El gobierno de Tucum\u00e1n impulsa el conocimiento cient\u00edfico con el af\u00e1n de asesorar a los especialistas sobre el uso de las nuevas tecnolog\u00edas que penetran en la Salud Digital y, que tienen el objetivo de mejorar la calidad de los servicios de salud p\u00fablica. El gobierno de Tucum\u00e1n \u2013provincia de Argentina\u2013 presta importancia a las pol\u00edticas p\u00fablicas relacionadas con la implementaci\u00f3n de la Salud Digital en todos sus servicios de salud. Es por eso, que desarroll\u00f3 el X Octubre Tecnol\u00f3gico, congreso que sirve como plataforma y punto de reuni\u00f3n entre especialistas de las nuevas Tecnolog\u00edas de la Informaci\u00f3n y la Comunicaci\u00f3n (TIC), y m\u00e9dicos, con el objetivo de compartir experiencias y conocimientos. Los debates en los que se pueden participar, tocan temas de actualidad que ponen como punto clave al paciente convirti\u00e9ndolo como eje central de toda experiencia cl\u00ednica y empoderarlo a trav\u00e9s de dispositivos y plataformas que pueda manejar con una buena asesor\u00eda. La finalidad es abrir caminos para poder adquirir herramientas y equipos que puedan llegar a las zonas m\u00e1s alejadas de la regi\u00f3n y, as\u00ed, ir eliminando la brecha de desigualdad en cuanto a acceso. Rossana Chahla, miembro del Ministerio de Salud Argentino, consider\u00f3 que las implicaciones de esta nueva era digital y tecnol\u00f3gica, hacen una buena s\u00edntesis para alcanzar objetivos comunes y \u201ctrabajar de manera conjunta, lo p\u00fablico con lo privado, y aunar esfuerzos para consensuar y discutir sobre las tem\u00e1ticas actuales\u201d. En la agenda p\u00fablica, se encuentra considerada la suma de esfuerzos entre ciencia y tecnolog\u00eda por medio de equipos interdisciplinarios (como medicina, biolog\u00eda e inform\u00e1tica) para desarrollar sistemas basados en la programaci\u00f3n y algoritmos. La transformaci\u00f3n digital permitir\u00e1 detectar para prevenir y anticipar cualquier enfermedad y, tambi\u00e9n, proporcionar a las personas infraestructura de calidad para que la red de internet permita realizar los trabajos en tiempo real. El eje principal, consistir\u00e1 en mantener la relaci\u00f3n m\u00e9dico\u2013paciente con un v\u00ednculo en donde ambos puedan participar y opinar para tomar decisiones ante posibles soluciones y puedan conocerse a fondo para establecer empat\u00eda. BIBLIOGRAF\u00cdA GOBIERNO DE TUCUM\u00c1N https:\/\/comunicaciontucuman.gob.ar\/2019\/10\/la-salud-en-la-era-digital-una-agenda-obligatoria\/<\/p>","protected":false},"author":1,"featured_media":6573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[152],"tags":[145],"class_list":["post-6572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avance-de-la-ciencia","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/6572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=6572"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/6572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/6573"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=6572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=6572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=6572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}