{"id":64650,"date":"2025-11-10T09:36:32","date_gmt":"2025-11-10T15:36:32","guid":{"rendered":"https:\/\/saluddigital.com\/?p=64650"},"modified":"2025-11-10T09:41:20","modified_gmt":"2025-11-10T15:41:20","slug":"dispositivo-de-bajo-costo-con-ia-detecta-enfermedades-oculares-mediante-imagenes-del-fondo-del-ojo","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/noticias\/dispositivo-de-bajo-costo-con-ia-detecta-enfermedades-oculares-mediante-imagenes-del-fondo-del-ojo\/","title":{"rendered":"Dispositivo de bajo costo con IA detecta enfermedades oculares mediante im\u00e1genes del fondo del ojo"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"64650\" class=\"elementor elementor-64650\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ec075ef elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5ec075ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1219fab6\" data-id=\"1219fab6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2cd834 elementor-widget elementor-widget-heading\" data-id=\"c2cd834\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Investigadores en India desarrollaron un sistema port\u00e1til que combina hardware y software optimizado para diagnosticar ocho tipos de padecimientos visuales con una precisi\u00f3n superior al 96%.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32572f04 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"32572f04\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e8ff34\" data-id=\"1e8ff34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29032ab5 elementor-widget elementor-widget-text-editor\" data-id=\"29032ab5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La p\u00e9rdida de visi\u00f3n afecta a m\u00e1s de mil millones de personas en todo el mundo, especialmente en regiones con recursos limitados. Muchos equipos de diagn\u00f3stico ocular, como las c\u00e1maras de retina o los tom\u00f3grafos \u00f3pticos, son costosos y requieren personal especializado, lo que dificulta su uso en cl\u00ednicas rurales. Para enfrentar este desaf\u00edo, un grupo de investigadores del Shri Ramdeobaba College of Engineering &amp; Management, en India, cre\u00f3 <strong>un dispositivo compacto e inteligente que utiliza inteligencia artificial (IA) para analizar im\u00e1genes del fondo del ojo o <em>fundus<\/em> y detectar m\u00faltiples enfermedades visuales en tiempo real<\/strong>.<\/p><p>El sistema, descrito recientemente en <a href=\"https:\/\/www.nature.com\/articles\/s41598-025-20990-y\"><em>Scientific Reports<\/em><\/a>, combina un modelo avanzado de aprendizaje profundo o <em>deep learning<\/em> denominado <strong>EfficientNet-B0<\/strong>, con un m\u00f3dulo de atenci\u00f3n espacial que mejora la precisi\u00f3n del an\u00e1lisis sin aumentar el consumo computacional. El dispositivo fue <strong>dise\u00f1ado para operar en entornos con recursos limitados<\/strong>, utilizando componentes econ\u00f3micos como una <strong>c\u00e1mara de 5 megap\u00edxeles<\/strong> y una computadora <strong>Raspberry Pi 5<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1810cb0b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1810cb0b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-28d3890\" data-id=\"28d3890\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dcb6465 elementor-widget elementor-widget-image\" data-id=\"5dcb6465\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/11\/11-25-11.jpg\" class=\"attachment-full size-full wp-image-64653\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/11\/11-25-11.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/11\/11-25-11-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/11\/11-25-11-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/11\/11-25-11-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/11\/11-25-11-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6d2fecde\" data-id=\"6d2fecde\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c9d896 elementor-widget elementor-widget-text-editor\" data-id=\"1c9d896\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El equipo logr\u00f3 integrar la captura de im\u00e1genes, la iluminaci\u00f3n controlada y el procesamiento en el propio dispositivo, evitando la necesidad de conexi\u00f3n a internet o servidores externos. Este enfoque, <em>edge AI<\/em>, permite diagn\u00f3sticos locales, protege la privacidad del paciente y facilita su implementaci\u00f3n en zonas rurales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-385aa105 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"385aa105\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29e96e18\" data-id=\"29e96e18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20bf8c93 elementor-widget elementor-widget-text-editor\" data-id=\"20bf8c93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durante las pruebas, el modelo fue entrenado con m\u00e1s de 13 mil im\u00e1genes de retina provenientes de bases de datos p\u00fablicas y hospitales. Alcanz\u00f3 una precisi\u00f3n del 96.2% al identificar ocho enfermedades oculares, entre ellas retinopat\u00eda diab\u00e9tica, glaucoma, degeneraci\u00f3n macular, cataratas y oclusi\u00f3n venosa retiniana. Adem\u00e1s, el sistema genera mapas de calor que destacan las \u00e1reas de la retina m\u00e1s relevantes para el diagn\u00f3stico, ayudando a los especialistas a interpretar los resultados con mayor transparencia.<\/p><p>El prototipo proces\u00f3 cada imagen en apenas cinco segundos, una velocidad suficiente para su uso durante ex\u00e1menes cl\u00ednicos. Los investigadores destacan que su enfoque ofrece una alternativa realista para centros de salud con acceso limitado a oftalm\u00f3logos o infraestructura avanzada.<\/p><p>En el futuro, los investigadores planean ampliar su base de datos y adaptar el modelo para detectar otras enfermedades oculares y sist\u00e9micas, como la neuropat\u00eda \u00f3ptica o la retinitis pigmentosa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61ca49d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"61ca49d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d09d865\" data-id=\"d09d865\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35a9b2cd elementor-widget elementor-widget-toggle\" data-id=\"35a9b2cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9001\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-9001\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-9001\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-9001\"><p><strong>NATURE<\/strong><\/p><p><a href=\"https:\/\/www.nature.com\/articles\/s41598-025-20990-y\">https:\/\/www.nature.com\/articles\/s41598-025-20990-y<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>EfficientNet-B0, el dispositivo de bajo costo con IA detecta enfermedades oculares mediante im\u00e1genes del fondo del ojo.<\/p>","protected":false},"author":1,"featured_media":64653,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3395,160],"tags":[145],"class_list":["post-64650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apps-moviles-e-internet-de-las-cosas","category-noticias","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/64650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=64650"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/64650\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/64653"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=64650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=64650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=64650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}