{"id":60238,"date":"2025-09-24T10:02:25","date_gmt":"2025-09-24T16:02:25","guid":{"rendered":"https:\/\/saluddigital.com\/?p=60238"},"modified":"2025-09-24T10:08:53","modified_gmt":"2025-09-24T16:08:53","slug":"nuclei-io-el-modelo-de-ia-de-stanford-que-impulsa-la-labor-de-los-patologos","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/big-data\/nuclei-io-el-modelo-de-ia-de-stanford-que-impulsa-la-labor-de-los-patologos\/","title":{"rendered":"Nuclei.io: Stanford&#039;s AI model that powers the work of pathologists"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"60238\" class=\"elementor elementor-60238\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12c93e40 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"12c93e40\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5faaf628\" data-id=\"5faaf628\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bd96560 elementor-widget elementor-widget-heading\" data-id=\"7bd96560\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Esta herramienta desarrollada en Stanford busca mayor rapidez, precisi\u00f3n y colaboraci\u00f3n en el diagn\u00f3stico.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e16f7ad elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3e16f7ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2329f83f\" data-id=\"2329f83f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dce419e elementor-widget elementor-widget-text-editor\" data-id=\"5dce419e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La identificaci\u00f3n de c\u00e9lulas anormales en biopsias y muestras sangu\u00edneas suele ser un proceso largo y complejo, en el que los pat\u00f3logos deben revisar miles de im\u00e1genes para encontrar peque\u00f1os indicios de enfermedad. Frente a este reto, investigadores de Stanford Medicine han desarrollado <strong>Nuclei.io<\/strong>, una plataforma de inteligencia artificial dise\u00f1ada para optimizar el trabajo en patolog\u00eda digital, mejorar la precisi\u00f3n diagn\u00f3stica y facilitar la colaboraci\u00f3n entre especialistas.<\/p><p>Nuclei.io fue creado por el Dr. James Zou, y el Dr. Thomas Montine, con un enfoque distinto a las herramientas convencionales, en lugar de reemplazar al especialista, aprende de \u00e9l y se adapta a sus m\u00e9todos de trabajo. El sistema se\u00f1ala regiones de inter\u00e9s en im\u00e1genes de alta resoluci\u00f3n, sugiere posibles \u00e1reas con c\u00e9lulas malignas o poco comunes y ofrece una segunda mirada en diagn\u00f3sticos complejos.<\/p><p>\u201cDebido a que estas im\u00e1genes patol\u00f3gicas son tan grandes, ocupan gigabytes y contienen mucha informaci\u00f3n, los pat\u00f3logos humanos necesitan bastante tiempo para interpretar lo que ocurre en cada imagen. A menudo tienen que determinar, a partir de esta gran imagen que contiene decenas de miles de c\u00e9lulas, cu\u00e1les son los peque\u00f1os detalles de las c\u00e9lulas que parecen diferentes y que podr\u00edan ser indicadores de c\u00e1ncer, tumores u otras enfermedades. Y aqu\u00ed es donde creemos que la IA puede ser de gran ayuda\u201d, explic\u00f3 el Dr. Zou.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5a8cd2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"d5a8cd2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7b8f1379\" data-id=\"7b8f1379\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ce46980 elementor-widget elementor-widget-image\" data-id=\"4ce46980\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/09\/09-25-35.jpg\" class=\"attachment-full size-full wp-image-60240\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/09\/09-25-35.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/09\/09-25-35-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/09\/09-25-35-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/09\/09-25-35-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/09\/09-25-35-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2d100d82\" data-id=\"2d100d82\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55271cbb elementor-widget elementor-widget-text-editor\" data-id=\"55271cbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una caracter\u00edstica innovadora es su funci\u00f3n de colaboraci\u00f3n en red, pues los pat\u00f3logos pueden compartir sus modelos con colegas de todo el mundo, comparar resultados y perfeccionar diagn\u00f3sticos en conjunto, casi como en una red social especializada. De esta forma, la experiencia acumulada por distintos expertos se convierte en un recurso colectivo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ae6e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5ae6e3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36f7acf3\" data-id=\"36f7acf3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-569fc618 elementor-widget elementor-widget-text-editor\" data-id=\"569fc618\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En pruebas realizadas en Stanford, los usuarios reportaron mayor eficiencia y seguridad en sus diagn\u00f3sticos, adem\u00e1s de una reducci\u00f3n en el tiempo necesario para revisar muestras. Esto representa un beneficio directo para los pacientes, pues agiliza la entrega de resultados y la elecci\u00f3n de tratamientos, adem\u00e1s de evitar pruebas adicionales y costosas.<\/p><p>El proyecto fue reconocido con el premio <strong>Stanford Medicine Catalyst<\/strong>, que apoya iniciativas con alto potencial de transformar la pr\u00e1ctica cl\u00ednica. Gracias a este respaldo, la herramienta avanza hacia su implementaci\u00f3n en hospitales y laboratorios.<\/p><p>\u201cLo que tambi\u00e9n descubrimos es que les hac\u00eda m\u00e1s seguros, ten\u00edan m\u00e1s confianza, y ese es el objetivo de todos desde el principio. Estoy emocionado por implementar Nuclei.io en Stanford Health Care, tenemos un plan para hacerlo y estoy emocionado por lo que vendr\u00e1 despu\u00e9s\u201d, detall\u00f3 el Dr. Montine.<\/p><p>De esta manera, la IA tiene el potencial de integrarse de manera pr\u00e1ctica y responsable en la medicina, fortaleciendo la labor humana en lugar de sustituirla. Para los pat\u00f3logos, significa trabajar con mayor rapidez y confianza, mientras que para los pacientes, diagn\u00f3sticos m\u00e1s certeros y oportunos.<\/p><p>\u201cLa IA tiene un enorme potencial para cambiar la medicina y la atenci\u00f3n sanitaria. Para que la IA alcance realmente todo su potencial, tambi\u00e9n necesitamos generar confianza. Aqu\u00ed es donde entra en juego el proceso <em>human in the loop<\/em>. El pat\u00f3logo humano seguir\u00e1 tomando las decisiones finales para realizar el diagn\u00f3stico definitivo, pero contar\u00e1 con orientaci\u00f3n en ese diagn\u00f3stico y esa decisi\u00f3n\u201d, finaliz\u00f3 el Dr. Zou.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c92de2f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3c92de2f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7752df3b\" data-id=\"7752df3b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30629048 elementor-widget elementor-widget-toggle\" data-id=\"30629048\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8111\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8111\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8111\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8111\"><p><strong>STANFORD<\/strong><\/p><p><a href=\"https:\/\/med.stanford.edu\/news\/all-news\/2025\/09\/ai-tool-pathology.html\">https:\/\/med.stanford.edu\/news\/all-news\/2025\/09\/ai-tool-pathology.html<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nuclei.io, el nuevo modelo de IA de Stanford Health Care que impulsa la labor de los pat\u00f3logos y busca revolucionar su trabajo.<\/p>","protected":false},"author":1,"featured_media":60240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[156,160],"tags":[145],"class_list":["post-60238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-big-data","category-noticias","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/60238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=60238"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/60238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/60240"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=60238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=60238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=60238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}