{"id":58427,"date":"2025-08-05T09:46:49","date_gmt":"2025-08-05T15:46:49","guid":{"rendered":"https:\/\/saluddigital.com\/?p=58427"},"modified":"2025-08-05T09:52:57","modified_gmt":"2025-08-05T15:52:57","slug":"ia-generativa-mejora-la-segmentacion-medica-en-entornos-con-escasez-de-datos","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/big-data\/ia-generativa-mejora-la-segmentacion-medica-en-entornos-con-escasez-de-datos\/","title":{"rendered":"IA generativa mejora la segmentaci\u00f3n m\u00e9dica en entornos con escasez de datos"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"58427\" class=\"elementor elementor-58427\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f763664 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1f763664\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c065be\" data-id=\"8c065be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-476ab7b1 elementor-widget elementor-widget-heading\" data-id=\"476ab7b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El nuevo modelo, GenSeg, mejora significativamente el an\u00e1lisis de im\u00e1genes m\u00e9dicas incluso con cantidades m\u00ednimas de datos etiquetados.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-539dd508 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"539dd508\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64d29da7\" data-id=\"64d29da7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44f4b67f elementor-widget elementor-widget-text-editor\" data-id=\"44f4b67f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un equipo de investigadores de instituciones como la Universidad de California en San Diego y Stanford desarroll\u00f3 un marco de <em>deep learning<\/em> o aprendizaje profundo llamado GenSeg, capaz de generar im\u00e1genes m\u00e9dicas y m\u00e1scaras de segmentaci\u00f3n de alta calidad. Este avance, publicado en <a href=\"https:\/\/www.nature.com\/articles\/s41467-025-61754-6\"><em>Nature Communications<\/em><\/a>, permite entrenar modelos precisos de segmentaci\u00f3n incluso en contextos con escasez extrema de datos, lo que podr\u00eda transformar el diagn\u00f3stico y tratamiento m\u00e9dico en entornos cl\u00ednicos con recursos limitados.<\/p>\n<p>La segmentaci\u00f3n sem\u00e1ntica de im\u00e1genes m\u00e9dicas es esencial para diagnosticar enfermedades, planificar tratamientos y asistir intervenciones quir\u00fargicas. Sin embargo, entrenar modelos de aprendizaje profundo confiables requiere grandes vol\u00famenes de im\u00e1genes etiquetadas por expertos, lo cual resulta costoso y complicado. Esta limitaci\u00f3n ha llevado al desarrollo de GenSeg, una soluci\u00f3n innovadora basada en inteligencia artificial generativa.<\/p>\n<p>\u201cEste proyecto naci\u00f3 de la necesidad de romper este cuello de botella y hacer m\u00e1s pr\u00e1cticas y accesibles potentes herramientas de segmentaci\u00f3n, especialmente para escenarios en los que los datos son escasos\u201d, expres\u00f3 Li Zhang, primer autor del estudio y estudiante de doctorado en UC San Diego.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1dd1a834 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1dd1a834\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fdb137a\" data-id=\"fdb137a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f2bab97 elementor-widget elementor-widget-image\" data-id=\"7f2bab97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/08\/08-25-07.jpg\" class=\"attachment-full size-full wp-image-58428\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/08\/08-25-07.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/08\/08-25-07-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/08\/08-25-07-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/08\/08-25-07-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/08\/08-25-07-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1553e41c\" data-id=\"1553e41c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-700b580d elementor-widget elementor-widget-text-editor\" data-id=\"700b580d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>GenSeg emplea un proceso de optimizaci\u00f3n multinivel (MLO, en ingl\u00e9s) que gu\u00eda la generaci\u00f3n de datos sint\u00e9ticos en funci\u00f3n del rendimiento de los modelos de segmentaci\u00f3n. A diferencia de m\u00e9todos tradicionales de aumento de datos o enfoques semi-supervisados, GenSeg genera pares imagen-m\u00e1scara directamente vinculados al objetivo de mejorar la segmentaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6861c31 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6861c31\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-63f17b6\" data-id=\"63f17b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20994349 elementor-widget elementor-widget-text-editor\" data-id=\"20994349\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los resultados fueron validados en 19 conjuntos de datos m\u00e9dicos, abarcando diversas enfermedades, \u00f3rganos y modalidades de imagen, como ecograf\u00edas, radiograf\u00edas, tomograf\u00edas \u00f3pticas y c\u00e1maras est\u00e1ndar. En todos los casos, GenSeg logr\u00f3 mejoras absolutas de 10 a 20% en precisi\u00f3n, incluso utilizando hasta 20 veces menos datos que otros m\u00e9todos.<\/p>\n<p>Adem\u00e1s, GenSeg demostr\u00f3 un rendimiento s\u00f3lido en escenarios fuera del dominio original de entrenamiento o <em>out-of-domain<\/em>, lo cual es crucial para su aplicaci\u00f3n en el mundo real. Por ejemplo, usando solo 9 o 40 im\u00e1genes anotadas, el modelo fue capaz de generalizar correctamente en conjuntos de datos completamente nuevos.<\/p>\n<p>Frente a herramientas de aumento de datos ampliamente usadas, como la rotaci\u00f3n o la inversi\u00f3n de im\u00e1genes, y modelos generativos tradicionales, GenSeg present\u00f3 un desempe\u00f1o consistentemente superior. Tambi\u00e9n super\u00f3 a m\u00e9todos semi-supervisados, sin necesidad de im\u00e1genes no etiquetadas adicionales, lo que refuerza su aplicabilidad pr\u00e1ctica.<\/p>\n<p>El marco GenSeg es agn\u00f3stico al modelo base, lo que permite integrarlo con arquitecturas populares como UNet, DeepLab o incluso modelos basados en transformadores como SwinUnet. Adem\u00e1s, puede extenderse a tareas de segmentaci\u00f3n en 3D, ampliando su utilidad en contextos cl\u00ednicos m\u00e1s complejos.<\/p>\n<p>\u201cEn lugar de tratar la generaci\u00f3n de datos y la formaci\u00f3n del modelo de segmentaci\u00f3n como dos tareas separadas, este sistema es el primero en integrarlas. El propio rendimiento de la segmentaci\u00f3n gu\u00eda el proceso de generaci\u00f3n de datos. De este modo se garantiza que los datos sint\u00e9ticos no s\u00f3lo sean realistas, sino que est\u00e9n espec\u00edficamente adaptados para mejorar la capacidad de segmentaci\u00f3n del modelo\u201d, indic\u00f3 Zhang.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d165aa1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2d165aa1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3266c012\" data-id=\"3266c012\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44606c86 elementor-widget elementor-widget-toggle\" data-id=\"44606c86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1141\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1141\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1141\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1141\"><p><strong>UC SAN DIEGO<\/strong><\/p>\n<p><a href=\"https:\/\/today.ucsd.edu\/story\/new-ai-tool-learns-to-read-medical-images-with-far-less-data\">https:\/\/today.ucsd.edu\/story\/new-ai-tool-learns-to-read-medical-images-with-far-less-data<\/a><\/p>\n<p><strong>NATURE<\/strong><\/p>\n<p><a href=\"https:\/\/www.nature.com\/articles\/s41467-025-61754-6\">https:\/\/www.nature.com\/articles\/s41467-025-61754-6<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>GenSeg,  la IA generativa creada en UC San Diego que mejora la segmentaci\u00f3n m\u00e9dica  y el an\u00e1lisis de im\u00e1genes en entornos con escasez de datos.<\/p>","protected":false},"author":1,"featured_media":58428,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[156,160],"tags":[145],"class_list":["post-58427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-big-data","category-noticias","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/58427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=58427"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/58427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/58428"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=58427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=58427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=58427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}