{"id":57818,"date":"2025-07-15T14:52:34","date_gmt":"2025-07-15T20:52:34","guid":{"rendered":"https:\/\/saluddigital.com\/?p=57818"},"modified":"2025-07-15T14:55:26","modified_gmt":"2025-07-15T20:55:26","slug":"fda-actualiza-su-lista-de-dispositivos-medicos-con-ia-ya-son-mas-de-mil-200-los-autorizados","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/big-data\/fda-actualiza-su-lista-de-dispositivos-medicos-con-ia-ya-son-mas-de-mil-200-los-autorizados\/","title":{"rendered":"FDA actualiza su lista de dispositivos m\u00e9dicos con IA: ya son m\u00e1s de mil 200 los autorizados"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"57818\" class=\"elementor elementor-57818\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d881e18 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6d881e18\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e2c2eea\" data-id=\"1e2c2eea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e9bcda1 elementor-widget elementor-widget-heading\" data-id=\"7e9bcda1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La agencia estadounidense destaca un crecimiento acelerado en el uso de IA en medicina, especialmente en cardiolog\u00eda e imagenolog\u00eda.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-510bd911 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"510bd911\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-251cf0fc\" data-id=\"251cf0fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4686af8a elementor-widget elementor-widget-text-editor\" data-id=\"4686af8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA, en ingl\u00e9s) ha autorizado cerca de 1,250 algoritmos de inteligencia artificial (IA) para su uso en atenci\u00f3n m\u00e9dica directa. M\u00e1s del 80 % de estos dispositivos est\u00e1n destinados a la interpretaci\u00f3n de im\u00e1genes m\u00e9dicas, aunque especialidades como la cardiolog\u00eda muestran un avance notable. La informaci\u00f3n fue publicada en la actualizaci\u00f3n m\u00e1s reciente de la lista oficial de dispositivos m\u00e9dicos habilitados con IA, la cual busca brindar mayor transparencia y orientaci\u00f3n tanto a proveedores de salud como a desarrolladores.<\/p><p>Seg\u00fan la FDA, la lista de dispositivos m\u00e9dicos con IA tiene como prop\u00f3sito principal identificar aquellas tecnolog\u00edas que han sido evaluadas y aprobadas para su comercializaci\u00f3n en Estados Unidos. Cada uno de los dispositivos incluidos ha cumplido con los requisitos regulatorios correspondientes, incluyendo una revisi\u00f3n centrada en su seguridad, eficacia y adecuaci\u00f3n al uso cl\u00ednico. Esta herramienta permite a profesionales de la salud, pacientes y empresas desarrolladoras conocer qu\u00e9 tecnolog\u00edas usan IA y c\u00f3mo est\u00e1n siendo utilizadas en contextos reales.<\/p><p>El crecimiento en la cantidad de aprobaciones ha sido sostenido y acelerado. Mientras que en 2019 la FDA autorizaba un promedio de 7 dispositivos por mes, para 2022 ese n\u00famero subi\u00f3 a 13.5, y en 2024 fue de 21 mensuales. En lo que va de 2025, ese promedio ha aumentado a casi 30 por mes, con un r\u00e9cord de 39 aprobaciones solo en mayo. La lista m\u00e1s reciente suma 300 nuevos algoritmos cl\u00ednicos aprobados en el \u00faltimo a\u00f1o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67e97a50 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"67e97a50\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-613f6c4c\" data-id=\"613f6c4c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5672bf7c elementor-widget elementor-widget-text-editor\" data-id=\"5672bf7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aunque la mayor\u00eda de estos dispositivos est\u00e1n relacionados con radiolog\u00eda, la cardiolog\u00eda ocupa el segundo lugar en volumen de herramientas aprobadas. Algunos de los desarrollos m\u00e1s destacados incluyen <strong>DeepRhythmAI<\/strong>, que permite evaluar arritmias card\u00edacas en la nube mediante datos de ECG; <strong>EchoGo Amyloidosis<\/strong>, un sistema automatizado para detectar signos de amiloidosis card\u00edaca en pacientes mayores de 65 a\u00f1os; y <strong>Volta AF-Xplorer<\/strong>, que asiste en el an\u00e1lisis de mapas el\u00e9ctricos del coraz\u00f3n durante estudios de fibrilaci\u00f3n auricular.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78c7c575\" data-id=\"78c7c575\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-230a64fd elementor-widget elementor-widget-image\" data-id=\"230a64fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/07\/07-25-22.jpg\" class=\"attachment-full size-full wp-image-57820\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/07\/07-25-22.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/07\/07-25-22-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/07\/07-25-22-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/07\/07-25-22-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/07\/07-25-22-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-270efc83 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"270efc83\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29810677\" data-id=\"29810677\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30625ecb elementor-widget elementor-widget-text-editor\" data-id=\"30625ecb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tambi\u00e9n se destacan innovaciones aplicadas al monitoreo ambulatorio como <strong>AT-Patch<\/strong>, un parche que registra ECGs por varios d\u00edas y transmite los datos para an\u00e1lisis autom\u00e1tico; <strong>VitalRhythm<\/strong>, que opera en la nube para detectar arritmias en pacientes no hospitalizados; y <strong>Loss of Pulse Detection<\/strong>, una app para dispositivos de consumo como relojes inteligentes que detecta p\u00e9rdida de pulso y activa alertas o llamadas de emergencia.<\/p><p>La FDA tambi\u00e9n inform\u00f3 que trabajar\u00e1 en nuevas formas de etiquetar dispositivos que integran grandes modelos de lenguaje (LLMs, en ingl\u00e9s), como los que se usan en aplicaciones conversacionales o an\u00e1lisis multimodal, con el fin de reforzar la transparencia para usuarios y profesionales de la salud.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-568dcf0a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"568dcf0a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49a8ede4\" data-id=\"49a8ede4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4aad213e elementor-widget elementor-widget-toggle\" data-id=\"4aad213e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1251\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1251\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1251\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1251\"><p><strong>FDA<\/strong><\/p><p><a href=\"https:\/\/www.fda.gov\/medical-devices\/software-medical-device-samd\/artificial-intelligence-enabled-medical-devices\">https:\/\/www.fda.gov\/medical-devices\/software-medical-device-samd\/artificial-intelligence-enabled-medical-devices<\/a><\/p><p><strong>CARDIOVASCULAR BUSINESS<\/strong><\/p><p><a href=\"https:\/\/cardiovascularbusiness.com\/topics\/artificial-intelligence\/cardiology-still-no-2-fda-cleared-clinical-ai-algorithms-trailing-only-radiology\">https:\/\/cardiovascularbusiness.com\/topics\/artificial-intelligence\/cardiology-still-no-2-fda-cleared-clinical-ai-algorithms-trailing-only-radiology<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La FDA actualiza su lista de dispositivos m\u00e9dicos con IA, ya son m\u00e1s de mil 200 los autorizados en Estados Unidos.<\/p>","protected":false},"author":1,"featured_media":57820,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[156,160],"tags":[145],"class_list":["post-57818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-big-data","category-noticias","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/57818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=57818"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/57818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/57820"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=57818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=57818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=57818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}