{"id":51561,"date":"2025-03-03T12:00:12","date_gmt":"2025-03-03T18:00:12","guid":{"rendered":"https:\/\/saluddigital.com\/?p=51561"},"modified":"2025-10-13T13:43:08","modified_gmt":"2025-10-13T19:43:08","slug":"nueva-norma-global-busca-proteger-la-audicion-de-los-jugadores-de-videojuegos","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/noticias\/nueva-norma-global-busca-proteger-la-audicion-de-los-jugadores-de-videojuegos\/","title":{"rendered":"Nueva norma global busca proteger la audici\u00f3n de los jugadores de videojuegos"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"51561\" class=\"elementor elementor-51561\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4413f5b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4413f5b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a44aabd\" data-id=\"6a44aabd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff00c8b elementor-widget elementor-widget-heading\" data-id=\"ff00c8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La OMS y la UIT presentan un est\u00e1ndar para fomentar la escucha segura en videojuegos y E-sports en el marco del D\u00eda Mundial de la Audici\u00f3n 2025.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4346e00f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4346e00f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f654977\" data-id=\"4f654977\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77e06d4e elementor-widget elementor-widget-text-editor\" data-id=\"77e06d4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En el marco del D\u00eda Mundial de la Audici\u00f3n 2025, que se celebra el 3 de marzo, la Organizaci\u00f3n Mundial de la Salud (OMS) y la Uni\u00f3n Internacional de Telecomunicaciones (UIT) anunciaron la primera norma global para promover la escucha segura en actividades de videojuegos y E-sports. Esta medida tiene como objetivo reducir el riesgo de p\u00e9rdida auditiva entre los jugadores, especialmente en ni\u00f1os y j\u00f3venes, quienes son m\u00e1s vulnerables a los da\u00f1os por exposici\u00f3n prolongada a sonidos fuertes.<\/p><p>De acuerdo con la OMS, alrededor de 3 mil millones de personas juegan videojuegos en dispositivos como computadoras, consolas o tel\u00e9fonos m\u00f3viles. Sin embargo, la mayor\u00eda de estos dispositivos no cuenta con funciones que protejan la audici\u00f3n de los usuarios. La exposici\u00f3n prolongada a sonidos fuertes durante las sesiones de juego puede provocar p\u00e9rdida auditiva irreversible, un riesgo que afecta especialmente a los ni\u00f1os debido a su menor tolerancia al ruido.<\/p><p>\u201cTodo el mundo puede adoptar hoy medidas para garantizar una buena salud auditiva a lo largo de su vida\u201d, expres\u00f3 el Dr. J\u00e9r\u00f4me Salomon, Subdirector General de Cobertura Sanitaria Universal y Enfermedades Transmisibles y No Transmisibles de la OMS. \u201cLa norma de escucha segura de la OMS y la UIT apoya a los gobiernos, los fabricantes, la sociedad civil y otras partes interesadas para fomentar entornos de escucha seguros, de modo que las personas de todas las edades puedan proteger sus o\u00eddos y su audici\u00f3n, e incluso cuando jueguen a videojuegos, no corran el riesgo de perder la audici\u00f3n\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ed5efff elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7ed5efff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-533717e9\" data-id=\"533717e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15327b2e elementor-widget elementor-widget-image\" data-id=\"15327b2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/03\/03-25-01.jpg\" class=\"attachment-full size-full wp-image-51562\" alt=\"videojuegos\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/03\/03-25-01.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/03\/03-25-01-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/03\/03-25-01-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/03\/03-25-01-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/03\/03-25-01-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b053833 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"b053833\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b43bb09\" data-id=\"6b43bb09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14fbb3c2 elementor-widget elementor-widget-text-editor\" data-id=\"14fbb3c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La nueva norma ofrece recomendaciones para dispositivos de videojuegos y software de juegos. Para los dispositivos, se sugiere implementar:<\/p><ul><li>Sistemas de seguimiento del nivel de sonido para medir la exposici\u00f3n del jugador<\/li><li>Mensajes informativos sobre el uso de sonido y advertencias cuando se alcancen l\u00edmites peligrosos<\/li><li>Controles de volumen f\u00e1ciles de usar<\/li><li>Un modo de seguridad para auriculares que ajuste autom\u00e1ticamente el volumen al cambiar entre altavoces y auriculares<\/li><\/ul><p>En cuanto al software, se recomienda incluir:<\/p><ul><li>Advertencias sobre los riesgos de p\u00e9rdida auditiva por sonidos fuertes<\/li><li>Controles de volumen independientes para diferentes efectos de sonido<\/li><li>Dise\u00f1o de sonido adaptado para fomentar la escucha segura<\/li><li>Detecci\u00f3n autom\u00e1tica de cambios entre auriculares y altavoces con ajustes autom\u00e1ticos de volumen<\/li><\/ul><p>La norma forma parte de la iniciativa Make Listening Safe de la OMS, que busca mejorar los h\u00e1bitos de escucha, especialmente entre los j\u00f3venes. Esta nueva regulaci\u00f3n se suma a otros est\u00e1ndares publicados anteriormente para dispositivos de audio personal y eventos en vivo. La OMS y la UIT esperan que estas medidas ayuden a proteger la audici\u00f3n de millones de personas, promoviendo entornos de juego m\u00e1s seguros.<\/p><p>Consulta m\u00e1s informaci\u00f3n sobre esta campa\u00f1a: <a href=\"https:\/\/www.who.int\/campaigns\/world-hearing-day\/2025\">https:\/\/www.who.int\/campaigns\/world-hearing-day\/2025<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6eeb9ead elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6eeb9ead\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b829d12\" data-id=\"4b829d12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60837ccd elementor-widget elementor-widget-toggle\" data-id=\"60837ccd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1611\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1611\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1611\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1611\"><p><strong>WHO<\/strong><\/p><p><a href=\"https:\/\/www.who.int\/campaigns\/world-hearing-day\/2025\">https:\/\/www.who.int\/campaigns\/world-hearing-day\/2025<\/a><\/p><p><a href=\"https:\/\/www.who.int\/news\/item\/28-02-2025-new-who-and-itu-standard-aims-to-prevent-hearing-loss-among-gamers\">https:\/\/www.who.int\/news\/item\/28-02-2025-new-who-and-itu-standard-aims-to-prevent-hearing-loss-among-gamers<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nueva norma global de la OMS y UIT busca proteger la audici\u00f3n de los jugadores de videojuegos y competidores de e-sports.<\/p>","protected":false},"author":1,"featured_media":51562,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3395,160],"tags":[145],"class_list":["post-51561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apps-moviles-e-internet-de-las-cosas","category-noticias","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/51561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=51561"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/51561\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/51562"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=51561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=51561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=51561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}