{"id":51177,"date":"2025-01-24T09:32:13","date_gmt":"2025-01-24T15:32:13","guid":{"rendered":"https:\/\/saluddigital.com\/?p=51177"},"modified":"2025-10-17T19:48:00","modified_gmt":"2025-10-18T01:48:00","slug":"modelos-3d-son-utilizados-para-comprender-mejor-el-cancer-ocular","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/big-data\/modelos-3d-son-utilizados-para-comprender-mejor-el-cancer-ocular\/","title":{"rendered":"Modelos 3D son utilizados para comprender mejor el c\u00e1ncer ocular"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"51177\" class=\"elementor elementor-51177\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-140014cf elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"140014cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-90969c2\" data-id=\"90969c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55c879f7 elementor-widget elementor-widget-heading\" data-id=\"55c879f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Investigadores de Mayo Clinic desarrollaron un biobanco de organoides en 3D para mejorar los tratamientos contra melanoma uveal, un tipo de c\u00e1ncer ocular.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a661534 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2a661534\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee3f3f9\" data-id=\"ee3f3f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a7603f elementor-widget elementor-widget-text-editor\" data-id=\"3a7603f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Investigadores de Mayo Clinic desarrollaron un modelo de organoides en 3D para estudiar el melanoma uveal, uno de los tipos m\u00e1s comunes de c\u00e1ncer ocular en adultos. El melanoma uveal es un tipo de c\u00e1ncer que se desarrolla en la \u00favea, una capa media del ojo que incluye el iris, el cuerpo ciliar, y las coroides. A pesar de ser el tipo de c\u00e1ncer ocular m\u00e1s com\u00fan, se le considera relativamente raro, por lo que las alternativas de tratamiento son limitadas a radioterapia, cirug\u00eda o terapias focales.<\/p><p>En este sentido, el modelo 3D de organoides es utilizando para comprender mejor c\u00f3mo funciona la enfermedad y desarrollar mejores tratamientos, especialmente para las necesidades no satisfechas de los pacientes.<\/p><p>Los organoides 3D son obtenidos a trav\u00e9s del tejido del paciente, por lo que reflejan con precisi\u00f3n caracter\u00edsticas biol\u00f3gicas y gen\u00e9ticas \u00fanicas de paciente. Cuando se derivan de un tumor canceroso de un paciente, los organoides se comportar\u00e1n y responder\u00e1n los tratamientos fuera del cuerpo en un laboratorio (in vitro) de la misma forma en la que lo har\u00eda el tumor original dentro del cuerpo (in vivo).<\/p><p>\u201cLa esperanza es que estos modelos de organoides derivados de pacientes representen mejor el c\u00e1ncer humano en el laboratorio\u201d, explic\u00f3 la Dra. Lauren Dalvin, onc\u00f3loga ocular y cirujana cient\u00edfica del Centro Oncol\u00f3gico Integral de Mayo Clinic. Adem\u00e1s, explic\u00f3 que estos modelos 3D ayudan para la prueba de f\u00e1rmacos y para descubrir nuevos tratamientos con mayores tasad de \u00e9xito en los ensayos cl\u00ednicos lo que posiblemente se traduzca en mejores resultados para pacientes con melanoma uveal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e093400 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6e093400\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-56a33047\" data-id=\"56a33047\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71496d20 elementor-widget elementor-widget-image\" data-id=\"71496d20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/01\/01-25-33.jpg\" class=\"attachment-full size-full wp-image-51179\" alt=\"Modelos 3D\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/01\/01-25-33.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/01\/01-25-33-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/01\/01-25-33-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/01\/01-25-33-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2025\/01\/01-25-33-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6051e293\" data-id=\"6051e293\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17dafc33 elementor-widget elementor-widget-text-editor\" data-id=\"17dafc33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Dra. Dalvin en colaboraci\u00f3n con el Dr. Martin Fern\u00e1ndez-Zapico, bi\u00f3logo oncol\u00f3gico en Mayo Clinic, desarrollaron un biobanco de organoides derivados de pacientes con melanoma uveal. El objetivo es desarrollar un recurso de investigaci\u00f3n que represente la variabilidad del mundo real de este tipo de c\u00e1ncer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bcb6814 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5bcb6814\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eab5a8b\" data-id=\"eab5a8b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97ac8a3 elementor-widget elementor-widget-text-editor\" data-id=\"97ac8a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un art\u00edculo publicado en <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/39601636\/\"><em>Ophthalmology &amp; Visual Science<\/em><\/a>, detalla el desarrollo del biobanco. Para la creaci\u00f3n de los organoides recolectaron tejidos tumorales desde el 1 de julio de 2019 hasta el 1 de julio de 2024. El estudio determino que:<\/p><ul><li>Podr\u00edan generarse, conservar su estabilidad a trav\u00e9s de muchos usos y ser un recurso vivo renovable capaz de regenerarse seg\u00fan sea necesario<\/li><li>Mantuvieron las caracter\u00edsticas cl\u00ednicamente relevantes de los tumores originales, se agruparon en grupos moleculares apropiados seg\u00fan marcadores pron\u00f3sticos validados y se asemejaron a la enfermedad humana en comparaci\u00f3n con los modelos animales in vivo<\/li><li>Sirvieron como modelos humanos adecuados para la detecci\u00f3n de medicamentos<\/li><\/ul><p>Los organoides tienen el potencial de cambiar la forma en la que se hace investigaci\u00f3n biom\u00e9dica ya que es un enfoque innovador para identificar y caracterizar potenciales tratamientos contra enfermedades neurodegenerativas y neurol\u00f3gicas, distintos tipos de c\u00e1ncer y enfermedades infecciosas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59a04aa2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"59a04aa2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2420466e\" data-id=\"2420466e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-246aa2cc elementor-widget elementor-widget-toggle\" data-id=\"246aa2cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6101\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6101\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6101\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6101\"><p><strong>MAYO CLINIC<\/strong><\/p><p><a href=\"https:\/\/newsnetwork.mayoclinic.org\/discussion\/3d-models-of-uveal-melanoma-offer-hope-for-improved-treatments\/\">https:\/\/newsnetwork.mayoclinic.org\/discussion\/3d-models-of-uveal-melanoma-offer-hope-for-improved-treatments\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Modelos 3D son utilizados en Mayo Clinic para comprender mejor el c\u00e1ncer ocular y desarrollar tratamientos m\u00e1s efectivos.<\/p>","protected":false},"author":1,"featured_media":51179,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[156,160],"tags":[145],"class_list":["post-51177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-big-data","category-noticias","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/51177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=51177"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/51177\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/51179"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=51177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=51177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=51177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}