{"id":50217,"date":"2024-10-31T09:24:14","date_gmt":"2024-10-31T15:24:14","guid":{"rendered":"https:\/\/saluddigital.com\/?p=50217"},"modified":"2025-10-18T00:05:21","modified_gmt":"2025-10-18T06:05:21","slug":"reunion-anual-de-la-red-pulsenet-america-latina-y-el-caribe-presento-avances-en-vigilancia-genomica","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/comunidades-conectadas\/reunion-anual-de-la-red-pulsenet-america-latina-y-el-caribe-presento-avances-en-vigilancia-genomica\/","title":{"rendered":"Reuni\u00f3n Anual de la Red PulseNet Am\u00e9rica Latina y el Caribe present\u00f3 avances en vigilancia gen\u00f3mica"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"50217\" class=\"elementor elementor-50217\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e27e9f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5e27e9f5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38aac11b\" data-id=\"38aac11b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36ce4920 elementor-widget elementor-widget-heading\" data-id=\"36ce4920\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Especialistas en salud p\u00fablica fortalecen vigilancia gen\u00f3mica en la regi\u00f3n para reforzar la vigilancia de pat\u00f3genos.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29f022d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"29f022d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e4c4302\" data-id=\"6e4c4302\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66f0145 elementor-widget elementor-widget-text-editor\" data-id=\"66f0145\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En un esfuerzo por mejorar la respuesta ante brotes epid\u00e9micos, la Reuni\u00f3n Anual de la Red PulseNet Am\u00e9rica Latina y el Caribe (PNALC) reuni\u00f3 a expertos en salud p\u00fablica de 18 pa\u00edses. Con el apoyo de la Organizaci\u00f3n Panamericana de la Salud (OPS) y la Red Internacional de Vigilancia de Pat\u00f3genos de la Organizaci\u00f3n Mundial de la Salud, el evento se enfoc\u00f3 en fortalecer la vigilancia gen\u00f3mica de pat\u00f3genos transmitidos por alimentos mediante tecnolog\u00edas avanzadas.<\/p><p>Durante el evento, los representantes de Bolivia, Brasil, Chile, Colombia, Costa Rica, Ecuador, El Salvador, Guatemala, Honduras, M\u00e9xico, Panam\u00e1, Paraguay, Per\u00fa, Uruguay, Argentina, Nicaragua, Cuba, y Venezuela, evaluaron los avances y compartieron experiencias sobre el uso de herramientas gen\u00f3micas para detectar y analizar brotes. La Dra. Chinen, de la coordinaci\u00f3n de PNALC, subray\u00f3 la importancia de la cooperaci\u00f3n regional: \u201cLa cooperaci\u00f3n regional es fundamental para fortalecer las capacidades de vigilancia y tomar decisiones m\u00e1s efectivas en salud p\u00fablica\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dfb1dd3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5dfb1dd3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c415283\" data-id=\"2c415283\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-281f6f23 elementor-widget elementor-widget-image\" data-id=\"281f6f23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2024\/10\/10-24-44.jpg\" class=\"attachment-full size-full wp-image-50219\" alt=\"vigilancia gen\u00f3mica\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2024\/10\/10-24-44.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2024\/10\/10-24-44-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2024\/10\/10-24-44-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2024\/10\/10-24-44-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2024\/10\/10-24-44-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a5d5d2c\" data-id=\"a5d5d2c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73b0bd57 elementor-widget elementor-widget-text-editor\" data-id=\"73b0bd57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Asimismo, las sesiones incluyeron la presentaci\u00f3n de casos de \u00e9xito en el uso de plataformas como Oxford Nanopore y Terra Bio, que permiten detectar pat\u00f3genos como Salmonella, Campylobacter, y Vibrio cholerae, y ayudan a monitorear la resistencia antimicrobiana. Este enfoque integral, denominado \u201cUna Sola Salud\u201d, tambi\u00e9n incorpor\u00f3 la salud animal y ambiental como parte de una estrategia multidisciplinaria.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d35c742 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5d35c742\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76ecad97\" data-id=\"76ecad97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34978a86 elementor-widget elementor-widget-text-editor\" data-id=\"34978a86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El evento tambi\u00e9n cont\u00f3 con la participaci\u00f3n de organizaciones internacionales como la Asociaci\u00f3n de Laboratorios de Salud P\u00fablica (APHL), los Centros para el Control y la Prevenci\u00f3n de Enfermedades (CDC) de Estados Unidos y la Secretar\u00eda Ejecutiva del Consejo de Ministros de Salud de Centroam\u00e9rica (SE-COMISCA), lo cual fortaleci\u00f3 la cooperaci\u00f3n interinstitucional.<\/p><p>Finalmente, el encuentro concluy\u00f3 con un llamado a establecer una hoja de ruta para los pr\u00f3ximos a\u00f1os que priorice la adopci\u00f3n de nuevas tecnolog\u00edas y la cooperaci\u00f3n entre los pa\u00edses de PNALC. Este plan busca mejorar la vigilancia de enfermedades y la respuesta ante emergencias sanitarias, elevando el nivel de salud p\u00fablica en Am\u00e9rica Latina, el Caribe, y el mundo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6044cdbb elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6044cdbb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64d1f8dc\" data-id=\"64d1f8dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6700a6fe elementor-widget elementor-widget-toggle\" data-id=\"6700a6fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1721\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1721\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1721\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1721\"><p><strong>PAHO<\/strong><\/p><p><a href=\"https:\/\/www.paho.org\/es\/noticias\/29-10-2024-avances-vigilancia-genomica-regional-reunion-anual-pulsenet-america-latina\">https:\/\/www.paho.org\/es\/noticias\/29-10-2024-avances-vigilancia-genomica-regional-reunion-anual-pulsenet-america-latina<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La Reuni\u00f3n Anual de la Red PulseNet Am\u00e9rica Latina y el Caribe present\u00f3 avances en vigilancia gen\u00f3mica en la regi\u00f3n.<\/p>","protected":false},"author":1,"featured_media":50219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154,160,3394],"tags":[145],"class_list":["post-50217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidades-conectadas","category-noticias","category-redes-sociales","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/50217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=50217"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/50217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/50219"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=50217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=50217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=50217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}