{"id":48357,"date":"2024-08-01T10:06:30","date_gmt":"2024-08-01T16:06:30","guid":{"rendered":"https:\/\/saluddigital.com\/?p=48357"},"modified":"2025-10-18T00:57:20","modified_gmt":"2025-10-18T06:57:20","slug":"amazon-y-ge-healthcare-firman-colaboracion-estrategica-para-impulsar-ia-generativa-en-atencion-medica","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/noticias\/amazon-y-ge-healthcare-firman-colaboracion-estrategica-para-impulsar-ia-generativa-en-atencion-medica\/","title":{"rendered":"Amazon y GE HealthCare firman colaboraci\u00f3n estrat\u00e9gica para impulsar IA generativa en atenci\u00f3n m\u00e9dica"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"48357\" class=\"elementor elementor-48357\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58486eda elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"58486eda\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ca847b0\" data-id=\"7ca847b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-434658a1 elementor-widget elementor-widget-heading\" data-id=\"434658a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Amazon Web Services y GE HealthCare firmaron una colaboraci\u00f3n estrat\u00e9gica para utilizar herramientas de IA generativa en la atenci\u00f3n m\u00e9dica.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31abdbe elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"31abdbe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-516fcf07\" data-id=\"516fcf07\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7908cdc4 elementor-widget elementor-widget-text-editor\" data-id=\"7908cdc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>GE HealthCare y Amazon Web Services (AWS) acordaron una colaboraci\u00f3n estrat\u00e9gica para acelerar la transformaci\u00f3n de la atenci\u00f3n m\u00e9dica con inteligencia artificial (IA) generativa. De esta forma, la compa\u00f1\u00eda de salud seleccion\u00f3 a AWS como su proveedor estrat\u00e9gico de servicios en la nube para ofrecer modelos nuevos y dise\u00f1ados especialmente para el desarrollo de aplicaciones innovadoras de atenci\u00f3n m\u00e9dica.<\/p><p>De esta forma GE HealthCare busca implementar modelos de base cl\u00ednica en tecnolog\u00edas de IA generativa y machine learning de AWS para agilizar flujos de trabajo cl\u00ednicos y operativos en la atenci\u00f3n m\u00e9dica. Esta colaboraci\u00f3n permitir\u00e1 acelerar las innovaciones y agilizar las operaciones en atenci\u00f3n m\u00e9dica. Asimismo, este acuerdo persigue aumentar la precisi\u00f3n del diagn\u00f3stico y detecci\u00f3n de enfermedades, as\u00ed como reducir los obst\u00e1culos de acceso a atenci\u00f3n m\u00e9dica y reducir la carga de trabajo de los proveedores.<\/p><p>\u201cEsta nueva colaboraci\u00f3n con AWS nos permite aprovechar nuestro legado de innovaci\u00f3n al adoptar el poder de la IA para acelerar la creaci\u00f3n de tecnolog\u00edas m\u00e9dicas que esperamos que redefinan los flujos de trabajo cl\u00ednicos y la prestaci\u00f3n de atenci\u00f3n\u201d, afirm\u00f3 Peter Arduini, presidente y director ejecutivo de GE HealthCare.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-238c4a9c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"238c4a9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-423815d9\" data-id=\"423815d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a2b9a4 elementor-widget elementor-widget-text-editor\" data-id=\"6a2b9a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una de las herramientas que utilizar\u00e1 GE HealthCare es Amazon Bedrock, un servicio que proporciona acceso seguro a modelos de base para crear e implementar soluciones de IA generativa a la medida. \u201cCon AWS como su proveedor de nube estrat\u00e9gico, GE HealthCare puede construir modelos y aplicaciones de base cl\u00ednica transformadores para la industria de la atenci\u00f3n m\u00e9dica\u201d, explic\u00f3 Matt Garman, director ejecutivo de AWS.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4e0b85f1\" data-id=\"4e0b85f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-720de003 elementor-widget elementor-widget-image\" data-id=\"720de003\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2024\/08\/08-24-01.jpg\" class=\"attachment-full size-full wp-image-48359\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2024\/08\/08-24-01.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2024\/08\/08-24-01-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2024\/08\/08-24-01-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2024\/08\/08-24-01-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2024\/08\/08-24-01-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5824c31e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5824c31e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc60f09\" data-id=\"fc60f09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-262ce183 elementor-widget elementor-widget-text-editor\" data-id=\"262ce183\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Por otro lado, tambi\u00e9n utilizar\u00e1n Amazon Q Developer, un asistente con tecnolog\u00eda de IA generativa para acelerar el desarrollo de software. \u201cNuestro trabajo con AWS es un gran paso para ayudar a los m\u00e9dicos a hacer que la atenci\u00f3n m\u00e9dica sea m\u00e1s sencilla, m\u00e1s eficiente y profundamente personalizada. Se trata de avanzar en la forma en que cuidamos a las personas en todas partes, una soluci\u00f3n innovadora a la vez\u201d, expres\u00f3 el Dr. Taha Kass-Hout, director global de ciencia y tecnolog\u00eda de GE HealthCare.<\/p><p>Adem\u00e1s, con el objetivo de modernizar la implementaci\u00f3n de modelos de machine learning, GE HealthCare utilizar\u00e1 Amazon SageMaker. El uso de esta soluci\u00f3n pretende acelerar el desarrollo y la implementaci\u00f3n de aplicaciones de im\u00e1genes m\u00e9dicas y mejorar la interoperabilidad para sus clientes.<\/p><p>\u201cSomos optimistas sobre las formas en que la IA generativa podr\u00e1 transformar la atenci\u00f3n m\u00e9dica para mejor, y esperamos ver las nuevas herramientas y aplicaciones que surjan de las colaboraciones entre la industria y la atenci\u00f3n m\u00e9dica\u201d, dijo el Dr. Keith Dreyer, director de ciencia de datos de Mass General Brigham y l\u00edder del negocio de IA de Mass General Brigham.<\/p><p>Cabe destacar que el uso de IA en los procesos de GE HealthCare no es una noticia nueva, pues cuentan con diversos avances. Por ejemplo, un trabajo reciente incluy\u00f3 un proyecto centrado en una herramienta avanzada de segmentaci\u00f3n de im\u00e1genes de ultrasonido. Gracias a la tecnolog\u00eda del modelo base esta investigaci\u00f3n ha permitido asilar e identificar estructuras anat\u00f3micas con una precisi\u00f3n de m\u00e1s del 90%, requiriendo poca intervenci\u00f3n humana.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15f268b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"15f268b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-54bc435d\" data-id=\"54bc435d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-790e30ff elementor-widget elementor-widget-toggle\" data-id=\"790e30ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2031\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2031\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2031\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2031\"><p><strong>GE HEALTHCARE<\/strong><\/p><p><a href=\"https:\/\/www.gehealthcare.com\/about\/newsroom\/press-releases\/ge-healthcare-and-aws-announce-strategic-collaboration-to-accelerate-healthcare-transformation-with-generative-ai?npclid=botnpclid\">https:\/\/www.gehealthcare.com\/about\/newsroom\/press-releases\/ge-healthcare-and-aws-announce-strategic-collaboration-to-accelerate-healthcare-transformation-with-generative-ai?npclid=botnpclid<\/a><\/p><p><strong>AWS<\/strong><\/p><p><a href=\"https:\/\/aws.amazon.com\/es\/blogs\/industries\/aws-and-ge-healthcare-are-teaming-up-to-use-ai-to-improve-patient-care\/\">https:\/\/aws.amazon.com\/es\/blogs\/industries\/aws-and-ge-healthcare-are-teaming-up-to-use-ai-to-improve-patient-care\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Amazon Web Services y GE HealthCare firman colaboraci\u00f3n estrat\u00e9gica para impulsar IA generativa en atenci\u00f3n m\u00e9dica.<\/p>","protected":false},"author":1,"featured_media":48359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3395,160],"tags":[145],"class_list":["post-48357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apps-moviles-e-internet-de-las-cosas","category-noticias","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/48357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=48357"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/48357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/48359"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=48357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=48357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=48357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}