{"id":41028,"date":"2023-10-05T09:31:05","date_gmt":"2023-10-05T15:31:05","guid":{"rendered":"https:\/\/saluddigital.com\/?p=41028"},"modified":"2025-10-19T00:36:43","modified_gmt":"2025-10-19T06:36:43","slug":"tlaxcala-inicia-proyecto-de-telemedicina-para-migrantes-en-nueva-york","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/noticias\/tlaxcala-inicia-proyecto-de-telemedicina-para-migrantes-en-nueva-york\/","title":{"rendered":"Tlaxcala inicia proyecto de telemedicina para migrantes en Nueva York"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"41028\" class=\"elementor elementor-41028\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b07cbca elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4b07cbca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-441f38db\" data-id=\"441f38db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4abd8e7a elementor-widget elementor-widget-heading\" data-id=\"4abd8e7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El Gobierno del estado de Tlaxcala present\u00f3 un proyecto de telemedicina que beneficiar\u00e1 a migrantes tlaxcaltecas en Estados Unidos.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20318dad elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"20318dad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56b6bfd7\" data-id=\"56b6bfd7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61733efb elementor-widget elementor-widget-text-editor\" data-id=\"61733efb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La gobernadora de Tlaxcala, Lorena Cu\u00e9llar Cisneros se reuni\u00f3 con representantes del Sector Salud y la Direcci\u00f3n de Atenci\u00f3n a Migrantes (DAM) para presentar un proyecto de telemedicina que brindar\u00e1 atenci\u00f3n m\u00e9dica de primer nivel a distancia a los migrantes tlaxcaltecas que residen en Estados Unidos. Este servicio se llevar\u00e1 a cabo a trav\u00e9s de una cabina equipada con tecnolog\u00eda de Internet de las Cosas (IoT, en ingl\u00e9s) y se planea implementar en el consulado de Nueva York.<\/p><p>Cu\u00e9llar Cisneros explic\u00f3 que esta cabina de telemedicina permitir\u00e1 medir par\u00e1metros de salud como peso, estatura, temperatura y saturaci\u00f3n de ox\u00edgeno, entre otros, para realizar un diagn\u00f3stico preciso de la condici\u00f3n de salud del paciente. Por su parte, Lorena Aguido, representante de la empresa Bitmec M\u00e9xico, destac\u00f3 que los sensores encargados de determinar los signos vitales estar\u00e1n conectados a una plataforma en Guatemala, lo que permitir\u00e1 la clasificaci\u00f3n de resultados m\u00e9dicos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31800300 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"31800300\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79800285\" data-id=\"79800285\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17d384b3 elementor-widget elementor-widget-image\" data-id=\"17d384b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/10\/10-23-06_2.jpg\" class=\"attachment-full size-full wp-image-41030\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/10\/10-23-06_2.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/10\/10-23-06_2-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/10\/10-23-06_2-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/10\/10-23-06_2-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/10\/10-23-06_2-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46e90c0b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"46e90c0b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2352afee\" data-id=\"2352afee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4eb51dbc elementor-widget elementor-widget-text-editor\" data-id=\"4eb51dbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Adem\u00e1s, los pacientes que utilicen este servicio de teleconsulta m\u00e9dica podr\u00e1n acceder a su diagn\u00f3stico de manera virtual, a trav\u00e9s de una pantalla que mostrar\u00e1 los valores obtenidos durante la exploraci\u00f3n realizada por el m\u00e9dico en la teleconsulta. De igual manera, se podr\u00e1n emitir recetas m\u00e9dicas y solicitudes de an\u00e1lisis cl\u00ednicos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4420ee6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4420ee6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9055dee\" data-id=\"9055dee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed748c7 elementor-widget elementor-widget-image\" data-id=\"ed748c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/10\/10-23-06.jpg\" class=\"attachment-full size-full wp-image-41031\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/10\/10-23-06.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/10\/10-23-06-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/10\/10-23-06-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/10\/10-23-06-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/10\/10-23-06-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f5b810 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"9f5b810\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-443ac21\" data-id=\"443ac21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc9858c elementor-widget elementor-widget-text-editor\" data-id=\"bc9858c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"background-color: var(--bs-body-bg); color: var(--bs-body-color); font-weight: var(--bs-body-font-weight);\">Este proyecto representa un avance importante en el acceso a servicios de salud para la numerosa comunidad migrantes de Tlaxcala en Nueva York. De esta forma, Tlaxcala se convertir\u00eda en el primer estado de M\u00e9xico en implementar esta tecnolog\u00eda de telemedicina y brindar atenci\u00f3n m\u00e9dica desde M\u00e9xico para mexicanos en Estados Unidos.<\/span><\/p><p>Al adoptar la Salud Digital y ofrecer un servicio eficaz y \u00e1gil a trav\u00e9s de este modelo de atenci\u00f3n a distancia, el gobierno de Tlaxcal, abre las puertas a nuevos proyectos de telemedicina y acceso a la salud, para la comunidad que vive en el extranjero.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-27882d5a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"27882d5a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a2e322\" data-id=\"3a2e322\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78ef9193 elementor-widget elementor-widget-toggle\" data-id=\"78ef9193\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2021\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2021\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2021\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2021\"><p><strong>SISTEMA DE NOTICIAS TLAXCALA<\/strong><\/p><p><a href=\"https:\/\/www.sndigital.mx\/titulares\/93093-inicia-gobierno-del-estado-proyecto-de-telemedicina-para-migrantes.html\">https:\/\/www.sndigital.mx\/titulares\/93093-inicia-gobierno-del-estado-proyecto-de-telemedicina-para-migrantes.html<\/a><\/p><p><strong>THE DAY OF THE EAST<\/strong><\/p><p><a href=\"https:\/\/www.lajornadadeoriente.com.mx\/tlaxcala\/gobierno-del-estado-inicia-proyecto-de-telemedicina-para-migrantes\/\">https:\/\/www.lajornadadeoriente.com.mx\/tlaxcala\/gobierno-del-estado-inicia-proyecto-de-telemedicina-para-migrantes\/<\/a><\/p><p><strong>URBANO PUEBLA<\/strong><\/p><p><a href=\"https:\/\/www.urbanopuebla.com.mx\/gobierno\/inicia-gobierno-de-tlaxcala-proyecto-de-telemedicina-para-migrantes\/\">https:\/\/www.urbanopuebla.com.mx\/gobierno\/inicia-gobierno-de-tlaxcala-proyecto-de-telemedicina-para-migrantes\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El Gobierno del estado de Tlaxcala present\u00f3 un proyecto de telemedicina que beneficiar\u00e1 a migrantes tlaxcaltecas en Estados Unidos. La gobernadora de Tlaxcala, Lorena Cu\u00e9llar Cisneros se reuni\u00f3 con representantes del Sector Salud y la Direcci\u00f3n de Atenci\u00f3n a Migrantes (DAM) para presentar un proyecto de telemedicina que brindar\u00e1 atenci\u00f3n m\u00e9dica de primer nivel a distancia a los migrantes tlaxcaltecas que residen en Estados Unidos. Este servicio se llevar\u00e1 a cabo a trav\u00e9s de una cabina equipada con tecnolog\u00eda de Internet de las Cosas (IoT, en ingl\u00e9s) y se planea implementar en el consulado de Nueva York. Cu\u00e9llar Cisneros explic\u00f3 que esta cabina de telemedicina permitir\u00e1 medir par\u00e1metros de salud como peso, estatura, temperatura y saturaci\u00f3n de ox\u00edgeno, entre otros, para realizar un diagn\u00f3stico preciso de la condici\u00f3n de salud del paciente. Por su parte, Lorena Aguido, representante de la empresa Bitmec M\u00e9xico, destac\u00f3 que los sensores encargados de determinar los signos vitales estar\u00e1n conectados a una plataforma en Guatemala, lo que permitir\u00e1 la clasificaci\u00f3n de resultados m\u00e9dicos. Adem\u00e1s, los pacientes que utilicen este servicio de teleconsulta m\u00e9dica podr\u00e1n acceder a su diagn\u00f3stico de manera virtual, a trav\u00e9s de una pantalla que mostrar\u00e1 los valores obtenidos durante la exploraci\u00f3n realizada por el m\u00e9dico en la teleconsulta. De igual manera, se podr\u00e1n emitir recetas m\u00e9dicas y solicitudes de an\u00e1lisis cl\u00ednicos. Este proyecto representa un avance importante en el acceso a servicios de salud para la numerosa comunidad migrantes de Tlaxcala en Nueva York. De esta forma, Tlaxcala se convertir\u00eda en el primer estado de M\u00e9xico en implementar esta tecnolog\u00eda de telemedicina y brindar atenci\u00f3n m\u00e9dica desde M\u00e9xico para mexicanos en Estados Unidos. Al adoptar la Salud Digital y ofrecer un servicio eficaz y \u00e1gil a trav\u00e9s de este modelo de atenci\u00f3n a distancia, el gobierno de Tlaxcal, abre las puertas a nuevos proyectos de telemedicina y acceso a la salud, para la comunidad que vive en el extranjero. BIBLIOGRAF\u00cdA SISTEMA DE NOTICIAS TLAXCALA https:\/\/www.sndigital.mx\/titulares\/93093-inicia-gobierno-del-estado-proyecto-de-telemedicina-para-migrantes.html LA JORNADA DE ORIENTE https:\/\/www.lajornadadeoriente.com.mx\/tlaxcala\/gobierno-del-estado-inicia-proyecto-de-telemedicina-para-migrantes\/ URBANO PUEBLA https:\/\/www.urbanopuebla.com.mx\/gobierno\/inicia-gobierno-de-tlaxcala-proyecto-de-telemedicina-para-migrantes\/<\/p>","protected":false},"author":1,"featured_media":41031,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160,3396],"tags":[145],"class_list":["post-41028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-uso-de-plataformas-digitales","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/41028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=41028"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/41028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/41031"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=41028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=41028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=41028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}