{"id":40477,"date":"2023-08-24T09:24:49","date_gmt":"2023-08-24T15:24:49","guid":{"rendered":"https:\/\/saluddigital.com\/?p=40477"},"modified":"2025-10-19T00:47:15","modified_gmt":"2025-10-19T06:47:15","slug":"ops-presenta-avances-del-proyecto-de-regulacion-de-tecnologias-sanitarias","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/comunidades-conectadas\/ops-presenta-avances-del-proyecto-de-regulacion-de-tecnologias-sanitarias\/","title":{"rendered":"OPS presenta avances del proyecto de regulaci\u00f3n de tecnolog\u00edas sanitarias"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"40477\" class=\"elementor elementor-40477\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d225c63 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5d225c63\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ff15e47\" data-id=\"4ff15e47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3aebe6b8 elementor-widget elementor-widget-heading\" data-id=\"3aebe6b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La OPS busca favorecer la formaci\u00f3n de profesionales en material regulatoria de tecnolog\u00edas sanitarias en la regi\u00f3n de las Am\u00e9ricas. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3912ea88 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3912ea88\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18884ec4\" data-id=\"18884ec4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24af0574 elementor-widget elementor-widget-text-editor\" data-id=\"24af0574\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Organizaci\u00f3n Panamericana de la Salud llev\u00f3 a cabo una reuni\u00f3n entre las Autoridades Regulatorias Nacionales de Referencia Regional (Grupo de ARNr) y el Departamento de Innovaci\u00f3n y Acceso a Medicamentos y Tecnolog\u00edas Sanitarias (IMT) con el prop\u00f3sito de presentar los avances del proyecto de regulaci\u00f3n de tecnolog\u00edas sanitarias (REGTEC).<\/p><p>La reuni\u00f3n inform\u00f3 sobre los avances del proyecto de itinerario formativo para los profesionales de REGTEC en los pa\u00edses de la regi\u00f3n. Este proyecto ser\u00e1 conducido a trav\u00e9s del Campus Virtual de Salud P\u00fablica de la OPS (CVSP) y como se mencion\u00f3, est\u00e1 dirigido a profesionales que desempe\u00f1an funciones y actividades regulatorias sobre las tecnolog\u00edas sanitarias. Este esfuerzo busca contribuir en la formaci\u00f3n continua de los profesionales en la regulaci\u00f3n de medicamentos y otras tecnolog\u00edas sanitarias para la promoci\u00f3n de las mejores pr\u00e1cticas regulatorias en la regi\u00f3n de las Am\u00e9ricas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33b0b27c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"33b0b27c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7010ac05\" data-id=\"7010ac05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45cfadc0 elementor-widget elementor-widget-image\" data-id=\"45cfadc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/08\/08-23-38.jpg\" class=\"attachment-full size-full wp-image-40479\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/08\/08-23-38.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/08\/08-23-38-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/08\/08-23-38-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/08\/08-23-38-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/08\/08-23-38-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-69cb8efd\" data-id=\"69cb8efd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bc14703 elementor-widget elementor-widget-text-editor\" data-id=\"1bc14703\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El itinerario formativo se centrar\u00e1 en los desaf\u00edos y prioridades existentes en la regi\u00f3n, referentes a la regulaci\u00f3n de productos m\u00e9dicos, as\u00ed como en el potencial de los sistemas regulatorios en la promoci\u00f3n de nuevas tecnolog\u00edas sanitarias. Las actividades tambi\u00e9n est\u00e1n destinadas a reguladores de pa\u00edses cuya infraestructura o capacidades regulatorias son limitadas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22b59370 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"22b59370\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2959702c\" data-id=\"2959702c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bfbe466 elementor-widget elementor-widget-text-editor\" data-id=\"5bfbe466\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Como parte del inicio de REGTEC, se actualiz\u00f3 el Curso Virtual de Regulaci\u00f3n Sanitaria de Productos Biol\u00f3gicos y Biotecnol\u00f3gicos, que en sus ediciones anteriores cont\u00f3 con cerca de 250 participantes de 19 pa\u00edses.<\/p><p>Cabe mencionar que este proyecto cuenta con el financiamiento del Gobierno de Canad\u00e1, como parte de su contribuci\u00f3n a la Plataforma Regional de la OPS para el Avance en la Producci\u00f3n de Vacunas y otras Tecnolog\u00edas Sanitarias. Esta iniciativa busca aumentar la capacidad de los pa\u00edses de las Am\u00e9ricas para responder ra\u00eddamente y con autonom\u00eda a agencias de salud.<\/p><p>El dise\u00f1o del itinerario tiene como objetivo proponer un modelo de formaci\u00f3n que integre los conocimientos con las tareas, las habilidades, los comportamientos y las actitudes necesarias para el desempe\u00f1o de las actividades regulatorias. Adem\u00e1s, responde a la necesidad de un cambio de paradigma en respuesta a la demanda de formaci\u00f3n de profesionales expertos en material regulatoria en el continente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5799091e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5799091e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7fb640c6\" data-id=\"7fb640c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b4409f elementor-widget elementor-widget-toggle\" data-id=\"7b4409f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1291\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1291\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1291\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1291\"><p><strong>PAHO<\/strong><\/p><p><a href=\"https:\/\/www.paho.org\/es\/noticias\/22-8-2023-ops-presento-itinerario-formativo-regtec-para-profesionales-regulacion\">https:\/\/www.paho.org\/es\/noticias\/22-8-2023-ops-presento-itinerario-formativo-regtec-para-profesionales-regulacion<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La OPS busca favorecer la formaci\u00f3n de profesionales en material regulatoria de tecnolog\u00edas sanitarias en la regi\u00f3n de las Am\u00e9ricas. La Organizaci\u00f3n Panamericana de la Salud llev\u00f3 a cabo una reuni\u00f3n entre las Autoridades Regulatorias Nacionales de Referencia Regional (Grupo de ARNr) y el Departamento de Innovaci\u00f3n y Acceso a Medicamentos y Tecnolog\u00edas Sanitarias (IMT) con el prop\u00f3sito de presentar los avances del proyecto de regulaci\u00f3n de tecnolog\u00edas sanitarias (REGTEC). La reuni\u00f3n inform\u00f3 sobre los avances del proyecto de itinerario formativo para los profesionales de REGTEC en los pa\u00edses de la regi\u00f3n. Este proyecto ser\u00e1 conducido a trav\u00e9s del Campus Virtual de Salud P\u00fablica de la OPS (CVSP) y como se mencion\u00f3, est\u00e1 dirigido a profesionales que desempe\u00f1an funciones y actividades regulatorias sobre las tecnolog\u00edas sanitarias. Este esfuerzo busca contribuir en la formaci\u00f3n continua de los profesionales en la regulaci\u00f3n de medicamentos y otras tecnolog\u00edas sanitarias para la promoci\u00f3n de las mejores pr\u00e1cticas regulatorias en la regi\u00f3n de las Am\u00e9ricas. El itinerario formativo se centrar\u00e1 en los desaf\u00edos y prioridades existentes en la regi\u00f3n, referentes a la regulaci\u00f3n de productos m\u00e9dicos, as\u00ed como en el potencial de los sistemas regulatorios en la promoci\u00f3n de nuevas tecnolog\u00edas sanitarias. Las actividades tambi\u00e9n est\u00e1n destinadas a reguladores de pa\u00edses cuya infraestructura o capacidades regulatorias son limitadas. Como parte del inicio de REGTEC, se actualiz\u00f3 el Curso Virtual de Regulaci\u00f3n Sanitaria de Productos Biol\u00f3gicos y Biotecnol\u00f3gicos, que en sus ediciones anteriores cont\u00f3 con cerca de 250 participantes de 19 pa\u00edses. Cabe mencionar que este proyecto cuenta con el financiamiento del Gobierno de Canad\u00e1, como parte de su contribuci\u00f3n a la Plataforma Regional de la OPS para el Avance en la Producci\u00f3n de Vacunas y otras Tecnolog\u00edas Sanitarias. Esta iniciativa busca aumentar la capacidad de los pa\u00edses de las Am\u00e9ricas para responder ra\u00eddamente y con autonom\u00eda a agencias de salud. El dise\u00f1o del itinerario tiene como objetivo proponer un modelo de formaci\u00f3n que integre los conocimientos con las tareas, las habilidades, los comportamientos y las actitudes necesarias para el desempe\u00f1o de las actividades regulatorias. Adem\u00e1s, responde a la necesidad de un cambio de paradigma en respuesta a la demanda de formaci\u00f3n de profesionales expertos en material regulatoria en el continente. BIBLIOGRAF\u00cdA OPS https:\/\/www.paho.org\/es\/noticias\/22-8-2023-ops-presento-itinerario-formativo-regtec-para-profesionales-regulacion<\/p>","protected":false},"author":1,"featured_media":40479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154,160,3394],"tags":[145],"class_list":["post-40477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidades-conectadas","category-noticias","category-redes-sociales","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/40477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=40477"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/40477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/40479"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=40477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=40477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=40477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}