{"id":38459,"date":"2023-05-11T09:35:25","date_gmt":"2023-05-11T15:35:25","guid":{"rendered":"https:\/\/saluddigital.com\/?p=38459"},"modified":"2025-10-19T23:13:31","modified_gmt":"2025-10-20T05:13:31","slug":"mayo-clinic-expande-su-red-de-datos-en-salud-para-impulsar-soluciones-basadas-en-ia","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/big-data\/mayo-clinic-expande-su-red-de-datos-en-salud-para-impulsar-soluciones-basadas-en-ia\/","title":{"rendered":"Mayo Clinic expands its health data network to drive AI-based solutions"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"38459\" class=\"elementor elementor-38459\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23d31b70 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"23d31b70\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d7df212\" data-id=\"1d7df212\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53ab05df elementor-widget elementor-widget-heading\" data-id=\"53ab05df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mayo Clinic Platform anunci\u00f3 que expandir\u00e1 su red de datos Connect, incluir\u00e1 hospitales en Brasil, Israel y Canad\u00e1.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-766ab2e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"766ab2e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56ef097e\" data-id=\"56ef097e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20a31456 elementor-widget elementor-widget-text-editor\" data-id=\"20a31456\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mayo Clinic Platform expandir\u00e1 su red de datos Mayo Clinic Platform_Connect, que ahora incluir\u00e1 al Hospital Israelita Albert Einstein, uno de los m\u00e1s importantes de Brasil; Sheba Medical Center de Israel y University Health Network (UHN) de Canad\u00e1. <a href=\"https:\/\/saluddigital.com\/es\/noticias\/mayo-clinic-anuncia-colaboracion-para-mejorar-la-atencion-medica-utilizando-ciencia-de-datos%ef%bf%bc\/\">Esta alianza<\/a> busca establecer una red de intercambio de datos que acelere el desarrollo de soluciones de salud basadas en inteligencia artificial (IA), utilizando ciencia de datos y a\u00f1os de informaci\u00f3n cl\u00ednica, con el prop\u00f3sito de mejorar los resultados de los pacientes en todo el mundo.<\/p><p>\u201cDescribimos que los datos necesarios para una IA justa y equitativa tienen profundidad (tipos de informaci\u00f3n), amplitud (n\u00famero de pacientes) y difusi\u00f3n (heterogeneidad). Para transformar la atenci\u00f3n m\u00e9dica a nivel mundial, debemos expandir nuestras redes de datos distribuidas a todos los continentes. Deben proteger la privacidad, adherirse a las leyes y regulaciones internacionales e incorporar conocimientos de todos los idiomas. Hoy, tres centros m\u00e9dicos de primer nivel en Am\u00e9rica del Sur, Canad\u00e1 y Medio Oriente se unen a nuestra red. Ellos inspirar\u00e1n y guiar\u00e1n a otras regiones y sistemas a unirse a nuestro esfuerzo mundial\u201d, expres\u00f3 John Halamka, presidente de Mayo Clinic Platform.<\/p><p>La estructuraci\u00f3n de los datos ahora permite que tipo de informaci\u00f3n m\u00e9dica compleja como registros de salud electr\u00f3nicos, im\u00e1genes de radiolog\u00eda o videos cl\u00ednicos sean m\u00e1s sencillos de analizar. Sin embargo, gracias al aprendizaje autom\u00e1tico Mayo Clinic Platform y los miembros de Connect han mejorado en la gesti\u00f3n y desarrollo de estas tareas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33784839 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"33784839\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-31af03d6\" data-id=\"31af03d6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71bd4a47 elementor-widget elementor-widget-text-editor\" data-id=\"71bd4a47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Por ejemplo, utilizan datos cl\u00ednicos agregados y no identificados para generar patrones y detectar enfermedades tempranamente y busca identificar las mejores opciones de tratamiento. En este sentido, Mayo Clinic Platform_Connect busca continuar ofreciendo datos cl\u00ednicos seguros y alojados en la nube que permitan la investigaci\u00f3n cl\u00ednica con mayor facilidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-140c7050\" data-id=\"140c7050\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32b3d646 elementor-widget elementor-widget-image\" data-id=\"32b3d646\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/05\/05-23-12.jpg\" class=\"attachment-full size-full wp-image-38460\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/05\/05-23-12.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/05\/05-23-12-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/05\/05-23-12-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/05\/05-23-12-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/05\/05-23-12-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b026647 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5b026647\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-612c960f\" data-id=\"612c960f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b910856 elementor-widget elementor-widget-text-editor\" data-id=\"b910856\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cEstamos encantados de ser parte de esta alianza hist\u00f3rica para transformar el futuro de la salud. Al crear una red verdaderamente global que romper\u00e1 las barreras del idioma y permitir\u00e1 la inclusi\u00f3n de poblaciones diversas, estamos desbloqueando el potencial de las soluciones de IA para revolucionar la atenci\u00f3n m\u00e9dica en todo el mundo\u201d, explic\u00f3 Eyal Zimlichman, director de transformaci\u00f3n y director de innovaci\u00f3n en Sheba Medical Center.<\/p><p>Por su parte, Sidney Klajner, presidente del Hospital Albert Einstein, explic\u00f3 que Connect permitir\u00e1 la inclusi\u00f3n de la poblaci\u00f3n Latinoam\u00e9rica, que actualmente se encuentra subrepresentada en la investigaci\u00f3n, espec\u00edficamente en estudio globales basados en tecnolog\u00eda e IA.<\/p><p>\u201cExiste una clara necesidad de considerar este perfil poblacional, teniendo en cuenta el contexto y las caracter\u00edsticas gen\u00e9ticas. Esto se ver\u00e1 reflejado en el desarrollo de proyectos de salud m\u00e1s equitativos, ampliando la oferta de recursos digitales de bajo costo para vacunas y medicamentos, por ejemplo. Nos sentimos honrados de ser miembros fundadores de esta importante red dirigida por Mayo Clinic\u201d, agreg\u00f3 Kajner.<\/p><p>Por \u00faltimo, Kevin Smith, presidente y director ejecutivo de UHN explic\u00f3 que: \u201cEl trabajo en equipo, la tecnolog\u00eda y el pensamiento audaz son esenciales para transformar las formas en que se brinda la atenci\u00f3n m\u00e9dica y poner a los pacientes en primer lugar\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36d42034 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"36d42034\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37070c4c\" data-id=\"37070c4c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e906e21 elementor-widget elementor-widget-toggle\" data-id=\"6e906e21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1851\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1851\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1851\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1851\"><p><strong>MAYO CLINIC<\/strong><\/p><p><a href=\"https:\/\/newsnetwork.mayoclinic.org\/discussion\/mayo-clinic-platform-expands-its-distributed-data-network-to-partner-to-globally-transform-patient-care\/\">https:\/\/newsnetwork.mayoclinic.org\/discussion\/mayo-clinic-platform-expands-its-distributed-data-network-to-partner-to-globally-transform-patient-care\/<\/a><br \/><br \/><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Mayo Clinic Platform anunci\u00f3 que expandir\u00e1 su red de datos Connect, incluir\u00e1 hospitales en Brasil, Israel y Canad\u00e1. Mayo Clinic Platform expandir\u00e1 su red de datos Mayo Clinic Platform_Connect, que ahora incluir\u00e1 al Hospital Israelita Albert Einstein, uno de los m\u00e1s importantes de Brasil; Sheba Medical Center de Israel y University Health Network (UHN) de Canad\u00e1. Esta alianza busca establecer una red de intercambio de datos que acelere el desarrollo de soluciones de salud basadas en inteligencia artificial (IA), utilizando ciencia de datos y a\u00f1os de informaci\u00f3n cl\u00ednica, con el prop\u00f3sito de mejorar los resultados de los pacientes en todo el mundo. \u201cDescribimos que los datos necesarios para una IA justa y equitativa tienen profundidad (tipos de informaci\u00f3n), amplitud (n\u00famero de pacientes) y difusi\u00f3n (heterogeneidad). Para transformar la atenci\u00f3n m\u00e9dica a nivel mundial, debemos expandir nuestras redes de datos distribuidas a todos los continentes. Deben proteger la privacidad, adherirse a las leyes y regulaciones internacionales e incorporar conocimientos de todos los idiomas. Hoy, tres centros m\u00e9dicos de primer nivel en Am\u00e9rica del Sur, Canad\u00e1 y Medio Oriente se unen a nuestra red. Ellos inspirar\u00e1n y guiar\u00e1n a otras regiones y sistemas a unirse a nuestro esfuerzo mundial\u201d, expres\u00f3 John Halamka, presidente de Mayo Clinic Platform. La estructuraci\u00f3n de los datos ahora permite que tipo de informaci\u00f3n m\u00e9dica compleja como registros de salud electr\u00f3nicos, im\u00e1genes de radiolog\u00eda o videos cl\u00ednicos sean m\u00e1s sencillos de analizar. Sin embargo, gracias al aprendizaje autom\u00e1tico Mayo Clinic Platform y los miembros de Connect han mejorado en la gesti\u00f3n y desarrollo de estas tareas. Por ejemplo, utilizan datos cl\u00ednicos agregados y no identificados para generar patrones y detectar enfermedades tempranamente y busca identificar las mejores opciones de tratamiento. En este sentido, Mayo Clinic Platform_Connect busca continuar ofreciendo datos cl\u00ednicos seguros y alojados en la nube que permitan la investigaci\u00f3n cl\u00ednica con mayor facilidad. \u201cEstamos encantados de ser parte de esta alianza hist\u00f3rica para transformar el futuro de la salud. Al crear una red verdaderamente global que romper\u00e1 las barreras del idioma y permitir\u00e1 la inclusi\u00f3n de poblaciones diversas, estamos desbloqueando el potencial de las soluciones de IA para revolucionar la atenci\u00f3n m\u00e9dica en todo el mundo\u201d, explic\u00f3 Eyal Zimlichman, director de transformaci\u00f3n y director de innovaci\u00f3n en Sheba Medical Center. Por su parte, Sidney Klajner, presidente del Hospital Albert Einstein, explic\u00f3 que Connect permitir\u00e1 la inclusi\u00f3n de la poblaci\u00f3n Latinoam\u00e9rica, que actualmente se encuentra subrepresentada en la investigaci\u00f3n, espec\u00edficamente en estudio globales basados en tecnolog\u00eda e IA. \u201cExiste una clara necesidad de considerar este perfil poblacional, teniendo en cuenta el contexto y las caracter\u00edsticas gen\u00e9ticas. Esto se ver\u00e1 reflejado en el desarrollo de proyectos de salud m\u00e1s equitativos, ampliando la oferta de recursos digitales de bajo costo para vacunas y medicamentos, por ejemplo. Nos sentimos honrados de ser miembros fundadores de esta importante red dirigida por Mayo Clinic\u201d, agreg\u00f3 Kajner. Por \u00faltimo, Kevin Smith, presidente y director ejecutivo de UHN explic\u00f3 que: \u201cEl trabajo en equipo, la tecnolog\u00eda y el pensamiento audaz son esenciales para transformar las formas en que se brinda la atenci\u00f3n m\u00e9dica y poner a los pacientes en primer lugar\u201d. BIBLIOGRAF\u00cdA MAYO CLINIC https:\/\/newsnetwork.mayoclinic.org\/discussion\/mayo-clinic-platform-expands-its-distributed-data-network-to-partner-to-globally-transform-patient-care\/<\/p>","protected":false},"author":1,"featured_media":38460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[156,160],"tags":[145],"class_list":["post-38459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-big-data","category-noticias","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/38459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=38459"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/38459\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/38460"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=38459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=38459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=38459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}