{"id":38380,"date":"2023-05-05T09:56:08","date_gmt":"2023-05-05T15:56:08","guid":{"rendered":"https:\/\/saluddigital.com\/?p=38380"},"modified":"2025-10-19T23:14:22","modified_gmt":"2025-10-20T05:14:22","slug":"instituto-nacional-de-salud-mental-en-peru-implementa-historias-clinicas-electronicas","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/noticias\/instituto-nacional-de-salud-mental-en-peru-implementa-historias-clinicas-electronicas\/","title":{"rendered":"Instituto Nacional de Salud Mental en Per\u00fa implementa historias cl\u00ednicas electr\u00f3nicas"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"38380\" class=\"elementor elementor-38380\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4136043b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4136043b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14af6081\" data-id=\"14af6081\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a9b4b62 elementor-widget elementor-widget-heading\" data-id=\"4a9b4b62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El Instituto Nacional de Salud Mental de Per\u00fa inici\u00f3 una estrategia de digitalizaci\u00f3n en los expedientes cl\u00ednicos de sus pacientes.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3295d53c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3295d53c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73e4badc\" data-id=\"73e4badc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c11f750 elementor-widget elementor-widget-text-editor\" data-id=\"c11f750\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Instituto Nacional de Salud Mental o INSM es una instituci\u00f3n p\u00fablica dedicada a la investigaci\u00f3n, prevenci\u00f3n, diagn\u00f3stico, tratamiento y rehabilitaci\u00f3n de las enfermedades mentales en el pa\u00eds. Fue fundado hace casi 75 a\u00f1os y es considerado uno de los principales referentes en salud mental en la regi\u00f3n.<\/p><p>Durante las \u00faltimas semanas el INSM ha comenzado un proceso de digitalizaci\u00f3n gracias a una estrategia de apertura de historias cl\u00ednicas. Las historias cl\u00ednicas de los usuarios est\u00e1n siendo registradas a trav\u00e9s del n\u00famero del documento nacional de identidad (DNI), de esta forma m\u00e1s de 118 mil historias digitales han reemplazado progresivamente a las historias cl\u00ednicas tradicionales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-203f8e6b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"203f8e6b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4b1cfc4\" data-id=\"4b1cfc4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71b9ced3 elementor-widget elementor-widget-image\" data-id=\"71b9ced3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/05\/05-23-04.jpg\" class=\"attachment-full size-full wp-image-38381\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/05\/05-23-04.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/05\/05-23-04-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/05\/05-23-04-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/05\/05-23-04-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/05\/05-23-04-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d0a33b\" data-id=\"1d0a33b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f064972 elementor-widget elementor-widget-text-editor\" data-id=\"1f064972\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esta estrategia forma parte del marco del proceso de transici\u00f3n a la historia cl\u00ednica electr\u00f3nica que establece al DNU como una identificaci\u00f3n \u00fanica para los usuarios y pacientes del INSM. Adem\u00e1s, esta acci\u00f3n permitir\u00e1 la estandarizaci\u00f3n de datos en el instituto, facilitando as\u00ed la evaluaci\u00f3n de las prestaciones de salud que reciben los pacientes en el instituto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1dca19f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1dca19f4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-365c7fdc\" data-id=\"365c7fdc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-606420b1 elementor-widget elementor-widget-text-editor\" data-id=\"606420b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cEstamos avanzando en el camino de la transformaci\u00f3n digital para optimizar la eficacia de nuestros procesos por un mejor servicio de salud mental a los ciudadanos\u201d, explic\u00f3 la Dra. Betty Misaico Revate, directora general del INSM.<\/p><p>Por otra parte, los residentes extranjeros de Per\u00fa pueden acceder a este beneficio a trav\u00e9s del carnet de extranjer\u00eda. O bien, ciudadanos peruanos sin DNI pueden identificarse por medio del componente biom\u00e9trico que confirmar\u00e1 su identidad.<\/p><p>De esta manera, la digitalizaci\u00f3n tambi\u00e9n favorecer\u00e1 en el mejoramiento de la gesti\u00f3n de recursos, la toma de decisiones y la planificaci\u00f3n de estrategias dentro del INSM.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d8268d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1d8268d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-665d4a2c\" data-id=\"665d4a2c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3820f66 elementor-widget elementor-widget-toggle\" data-id=\"3820f66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5881\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-5881\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5881\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-5881\"><p><strong>ANDEAN<\/strong><\/p><p><a href=\"https:\/\/andina.pe\/agencia\/noticia-salud-mental-insm-implementa-registro-historias-clinicas-con-numero-dni-938005.aspx\">https:\/\/andina.pe\/agencia\/noticia-salud-mental-insm-implementa-registro-historias-clinicas-con-numero-dni-938005.aspx<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El Instituto Nacional de Salud Mental de Per\u00fa inici\u00f3 una estrategia de digitalizaci\u00f3n en los expedientes cl\u00ednicos de sus pacientes. El Instituto Nacional de Salud Mental o INSM es una instituci\u00f3n p\u00fablica dedicada a la investigaci\u00f3n, prevenci\u00f3n, diagn\u00f3stico, tratamiento y rehabilitaci\u00f3n de las enfermedades mentales en el pa\u00eds. Fue fundado hace casi 75 a\u00f1os y es considerado uno de los principales referentes en salud mental en la regi\u00f3n. Durante las \u00faltimas semanas el INSM ha comenzado un proceso de digitalizaci\u00f3n gracias a una estrategia de apertura de historias cl\u00ednicas. Las historias cl\u00ednicas de los usuarios est\u00e1n siendo registradas a trav\u00e9s del n\u00famero del documento nacional de identidad (DNI), de esta forma m\u00e1s de 118 mil historias digitales han reemplazado progresivamente a las historias cl\u00ednicas tradicionales. Esta estrategia forma parte del marco del proceso de transici\u00f3n a la historia cl\u00ednica electr\u00f3nica que establece al DNU como una identificaci\u00f3n \u00fanica para los usuarios y pacientes del INSM. Adem\u00e1s, esta acci\u00f3n permitir\u00e1 la estandarizaci\u00f3n de datos en el instituto, facilitando as\u00ed la evaluaci\u00f3n de las prestaciones de salud que reciben los pacientes en el instituto. \u201cEstamos avanzando en el camino de la transformaci\u00f3n digital para optimizar la eficacia de nuestros procesos por un mejor servicio de salud mental a los ciudadanos\u201d, explic\u00f3 la Dra. Betty Misaico Revate, directora general del INSM. Por otra parte, los residentes extranjeros de Per\u00fa pueden acceder a este beneficio a trav\u00e9s del carnet de extranjer\u00eda. O bien, ciudadanos peruanos sin DNI pueden identificarse por medio del componente biom\u00e9trico que confirmar\u00e1 su identidad. De esta manera, la digitalizaci\u00f3n tambi\u00e9n favorecer\u00e1 en el mejoramiento de la gesti\u00f3n de recursos, la toma de decisiones y la planificaci\u00f3n de estrategias dentro del INSM. BIBLIOGRAF\u00cdA ANDINA https:\/\/andina.pe\/agencia\/noticia-salud-mental-insm-implementa-registro-historias-clinicas-con-numero-dni-938005.aspx<\/p>","protected":false},"author":1,"featured_media":38381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160,3396],"tags":[145],"class_list":["post-38380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-uso-de-plataformas-digitales","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/38380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=38380"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/38380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/38381"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=38380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=38380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=38380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}