{"id":37225,"date":"2023-03-01T09:35:38","date_gmt":"2023-03-01T15:35:38","guid":{"rendered":"https:\/\/saluddigital.com\/?p=37225"},"modified":"2025-10-19T23:45:15","modified_gmt":"2025-10-20T05:45:15","slug":"ee-uu-inicia-plan-piloto-de-telesalud-de-tratamiento-antiviral-para-covid-19-desde-casa","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/comunidades-conectadas\/ee-uu-inicia-plan-piloto-de-telesalud-de-tratamiento-antiviral-para-covid-19-desde-casa\/","title":{"rendered":"US begins telehealth pilot of COVID-19 antiviral treatment from home"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"37225\" class=\"elementor elementor-37225\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75a604c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"75a604c4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69ce7fc0\" data-id=\"69ce7fc0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1870e3be elementor-widget elementor-widget-heading\" data-id=\"1870e3be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un programa piloto de telesalud permite la consulta y el tratamiento antiviral contra COVID-19 sin que los pacientes salgan de sus casas.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc62306 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"dc62306\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30ab53f0\" data-id=\"30ab53f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-786d2255 elementor-widget elementor-widget-text-editor\" data-id=\"786d2255\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A trav\u00e9s de una colaboraci\u00f3n entre los Institutos Nacionales de Salud (NIH), la Administraci\u00f3n para la Preparaci\u00f3n y Respuesta Estrat\u00e9gicas (ASPR) y las agencias locales de salud p\u00fablica, fue lanzado el programa <strong><em>Home Test to Treat<\/em><\/strong>, cuyo objetivo es ampliar el acceso a los servicios de COVID-19 en las comunidades vulnerables y reducir la propagaci\u00f3n comunitaria. El programa comenz\u00f3 en enero en el estado de Pensilvania, y los NIH planean inscribir alrededor de 100 mil participantes de todo el pa\u00eds durante 2023.<\/p><p>\u201cSe seleccionar\u00e1n comunidades adicionales en todo el pa\u00eds para participar en funci\u00f3n del nivel de necesidad de la comunidad, el acceso al tratamiento de atenci\u00f3n m\u00e9dica, las tasas esperadas de infecci\u00f3n por COVID-19 y los factores socioecon\u00f3micos. A trav\u00e9s de colaboraciones con los departamentos de salud locales, <em>Home Test to Treat<\/em> tiene como objetivo ofrecer servicios a aproximadamente 100,000 personas en los Estados Unidos el pr\u00f3ximo a\u00f1o\u201d, explicaron los NIH en un comunicado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68d65d2d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"68d65d2d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66b9e0f4\" data-id=\"66b9e0f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65804236 elementor-widget elementor-widget-image\" data-id=\"65804236\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/03\/02-23-40.jpg\" class=\"attachment-full size-full wp-image-37226\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/03\/02-23-40.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/03\/02-23-40-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/03\/02-23-40-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/03\/02-23-40-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2023\/03\/02-23-40-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2194c18b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2194c18b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62bdbd46\" data-id=\"62bdbd46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-229440b0 elementor-widget elementor-widget-text-editor\" data-id=\"229440b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Este programa brinda una intervenci\u00f3n de salud comunitaria totalmente virtual, que ofrecer\u00e1 19 tipos de servicio como pruebas r\u00e1pidas desde el hogar, sesiones de telesalud y tratamientos antivirales desde el hogar. Este programa de telesalud permite que m\u00e1s personas accedan a tratamientos antivirales luego de obtener una prueba de COVID-19 positiva.<\/p><p>\u00a0<\/p><p>\u201cEl programa Home Test to Treat permite a las personas enfermas una alternativa a salir para hacerse pruebas o recibir tratamiento, lo que podr\u00eda reducir la propagaci\u00f3n de la COVID-19 en la comunidad\u201d, explica el Dr. Bruce Tromberg, de los NIH.<\/p><p>Los servicios de telesalud que permiten el registro, acceso a kits de prueba, teleconsultas y entrega de tratamientos, ser\u00e1n proporcionados por eMed una compa\u00f1\u00eda especializada en telemedicina. Asimismo, investigadores de la UMass Chan Medical School evaluar\u00e1n datos sobre actitudes, respuestas y resultados cl\u00ednicos de los pacientes. Estos datos permitir\u00e1n perfeccionar el programa e identificar problemas espec\u00edficos en las comunidades que afectan la prestaci\u00f3n de servicios.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-328e99e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"328e99e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c1bc20c\" data-id=\"3c1bc20c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ecb147b elementor-widget elementor-widget-toggle\" data-id=\"7ecb147b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2121\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2121\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2121\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2121\"><p><strong>NIH<\/strong><\/p><p><a href=\"https:\/\/www.nih.gov\/news-events\/news-releases\/nih-launches-home-test-treat-pilot-covid-19-telehealth-program\">https:\/\/www.nih.gov\/news-events\/news-releases\/nih-launches-home-test-treat-pilot-covid-19-telehealth-program<\/a><\/p><p><strong>JAMA NETWORK<\/strong><\/p><p><a href=\"https:\/\/jamanetwork.com\/journals\/jama\/fullarticle\/2800766\">https:\/\/jamanetwork.com\/journals\/jama\/fullarticle\/2800766<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Un programa piloto de telesalud permite la consulta y el tratamiento antiviral contra COVID-19 sin que los pacientes salgan de sus casas. A trav\u00e9s de una colaboraci\u00f3n entre los Institutos Nacionales de Salud (NIH), la Administraci\u00f3n para la Preparaci\u00f3n y Respuesta Estrat\u00e9gicas (ASPR) y las agencias locales de salud p\u00fablica, fue lanzado el programa Home Test to Treat, cuyo objetivo es ampliar el acceso a los servicios de COVID-19 en las comunidades vulnerables y reducir la propagaci\u00f3n comunitaria. El programa comenz\u00f3 en enero en el estado de Pensilvania, y los NIH planean inscribir alrededor de 100 mil participantes de todo el pa\u00eds durante 2023. \u201cSe seleccionar\u00e1n comunidades adicionales en todo el pa\u00eds para participar en funci\u00f3n del nivel de necesidad de la comunidad, el acceso al tratamiento de atenci\u00f3n m\u00e9dica, las tasas esperadas de infecci\u00f3n por COVID-19 y los factores socioecon\u00f3micos. A trav\u00e9s de colaboraciones con los departamentos de salud locales, Home Test to Treat tiene como objetivo ofrecer servicios a aproximadamente 100,000 personas en los Estados Unidos el pr\u00f3ximo a\u00f1o\u201d, explicaron los NIH en un comunicado. Este programa brinda una intervenci\u00f3n de salud comunitaria totalmente virtual, que ofrecer\u00e1 19 tipos de servicio como pruebas r\u00e1pidas desde el hogar, sesiones de telesalud y tratamientos antivirales desde el hogar. Este programa de telesalud permite que m\u00e1s personas accedan a tratamientos antivirales luego de obtener una prueba de COVID-19 positiva. \u201cEl programa Home Test to Treat permite a las personas enfermas una alternativa a salir para hacerse pruebas o recibir tratamiento, lo que podr\u00eda reducir la propagaci\u00f3n de la COVID-19 en la comunidad\u201d, explica el Dr. Bruce Tromberg, de los NIH. Los servicios de telesalud que permiten el registro, acceso a kits de prueba, teleconsultas y entrega de tratamientos, ser\u00e1n proporcionados por eMed una compa\u00f1\u00eda especializada en telemedicina. Asimismo, investigadores de la UMass Chan Medical School evaluar\u00e1n datos sobre actitudes, respuestas y resultados cl\u00ednicos de los pacientes. Estos datos permitir\u00e1n perfeccionar el programa e identificar problemas espec\u00edficos en las comunidades que afectan la prestaci\u00f3n de servicios. BIBLIOGRAF\u00cdA NIH https:\/\/www.nih.gov\/news-events\/news-releases\/nih-launches-home-test-treat-pilot-covid-19-telehealth-program JAMA NETWORK https:\/\/jamanetwork.com\/journals\/jama\/fullarticle\/2800766<\/p>","protected":false},"author":1,"featured_media":37226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154,160,3394],"tags":[145],"class_list":["post-37225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidades-conectadas","category-noticias","category-redes-sociales","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/37225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=37225"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/37225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/37226"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=37225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=37225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=37225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}