{"id":26711,"date":"2022-05-27T09:24:01","date_gmt":"2022-05-27T14:24:01","guid":{"rendered":"https:\/\/saluddigital.com\/?p=26711"},"modified":"2025-10-20T11:52:50","modified_gmt":"2025-10-20T17:52:50","slug":"aceleradora-de-amazon-se-centrara-en-equidad-en-salud","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/noticias\/aceleradora-de-amazon-se-centrara-en-equidad-en-salud\/","title":{"rendered":"Amazon accelerator to focus on health equity"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"26711\" class=\"elementor elementor-26711\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-597ef57e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"597ef57e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2cb3fcf0\" data-id=\"2cb3fcf0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c7a09ad elementor-widget elementor-widget-heading\" data-id=\"6c7a09ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">This year&#039;s Amazon Web Services accelerator cohort will focus on innovations that advance health equity, as well as the use of digital technologies. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c85c3e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4c85c3e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5cdb7584\" data-id=\"5cdb7584\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20e9762a elementor-widget elementor-widget-text-editor\" data-id=\"20e9762a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Amazon Web Services (AWS) Healthcare Accelerator is accepting requests for projects and innovations that aim to bring higher quality health services to underserved communities, reduce disparities as social determinants in access to health, and create data that promote fairer health systems.<\/p><p>The new cohort will accept ten companies or startups that meet the criteria of closing gaps in access to health care and the use of data for equity in health care. Public and private organizations, companies, startups and others are eligible to apply.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31c5bdd0 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"31c5bdd0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3af0fc98\" data-id=\"3af0fc98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25080917 elementor-widget elementor-widget-image\" data-id=\"25080917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2022\/05\/05-22-38.jpg\" class=\"attachment-full size-full wp-image-26713\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2022\/05\/05-22-38.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2022\/05\/05-22-38-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2022\/05\/05-22-38-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2022\/05\/05-22-38-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2022\/05\/05-22-38-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e02763f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2e02763f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-288bb975\" data-id=\"288bb975\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-139f9b9 elementor-widget elementor-widget-text-editor\" data-id=\"139f9b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>This will be only the second cohort of this AWS project, <a href=\"https:\/\/saluddigital.com\/es\/uso-de-plataformas-digitales\/amazon-ofrecera-acelerador-a-diez-empresas-emergentes-de-salud-digital\/\">the first was held last year with an emphasis on Digital Health<\/a> and pediatric health. \u201cThe goal of the AWS Healthcare Accelerator is to cultivate and promote innovative startup solutions that achieve the quadruple goal of improving the patient experience, improving the physician experience, improving health outcomes, and lowering the cost of care,\u201d AWS said. last year.<\/p><p>Applications for the second cohort are due by July 1. On July 29, the ten projects will be notified and the program will start in August. Finally, the accelerator program will happen between September 12 and July 6.<\/p><p>Learn more: <a href=\"https:\/\/www.kidsx.health\/aws-accelerator\/\">https:\/\/www.kidsx.health\/aws-accelerator\/<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2cc9ffca elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2cc9ffca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d875855\" data-id=\"3d875855\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-252accda elementor-widget elementor-widget-toggle\" data-id=\"252accda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6231\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6231\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6231\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6231\"><p><strong>MOBIHEALTH NEWS <\/strong><\/p><p><a href=\"https:\/\/www.mobihealthnews.com\/news\/aws-new-accelerator-cohort-will-focus-health-equity-and-more-digital-health-briefs\">https:\/\/www.mobihealthnews.com\/news\/aws-new-accelerator-cohort-will-focus-health-equity-and-more-digital-health-briefs<\/a><\/p><p><strong>KIDSX<\/strong><\/p><p><a href=\"https:\/\/www.kidsx.health\/aws-accelerator\/\">https:\/\/www.kidsx.health\/aws-accelerator\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La cohorte de la aceleradora de Amazon Web Services este a\u00f1o se enfocar\u00e1 en innovaciones que promuevan la equidad en salud, as\u00ed como el uso de tecnolog\u00edas digitales. El Healthcare Accelerator de Amazon Web Services (AWS), se encuentra aceptando solicitudes de proyectos e innovaciones que tienen como prop\u00f3sito acercar servicios de salud de mayor calidad a comunicades desentendidas, reducir disparidades como determinantes sociales en el acceso a la salud, y la creaci\u00f3n de datos que promuevan sistemas de salud m\u00e1s justos. La nueva cohorte aceptar\u00e1 diez empresas o startups que cumplan con los criterios de cerrar brechas en el acceso a la atenci\u00f3n m\u00e9dica y el uso de datos para la equidad en el cuidado de la salud. Organizaciones p\u00fablicas, privadas, empresas, startups y dem\u00e1s, son elegibles para aplicar. Esta ser\u00e1 apenas la segunda cohorte de este proyecto de AWS, la primera se realiz\u00f3 el a\u00f1o pasado con \u00e9nfasis en Salud Digital y salud pedi\u00e1trica. \u201cEl objetivo de AWS Healthcare Accelerator es cultivar y promover soluciones de inicio innovadoras que logren el objetivo cu\u00e1druple de mejorar la experiencia del paciente, mejorar la experiencia del m\u00e9dico, mejorar los resultados de salud y reducir el costo de la atenci\u00f3n\u201d, indic\u00f3 AWS el a\u00f1o pasado. Las solicitudes para la segunda cohorte se deben presentar antes del 1 de julio. El 29 de julio los diez proyectos ser\u00e1n notificados y el programa iniciar\u00e1 en agosto. Finalmente, el programa de acelerador suceder\u00e1 entre el 12 de septiembre y el 6 de julio. Conoce m\u00e1s: https:\/\/www.kidsx.health\/aws-accelerator\/ BIBLIOGRAF\u00cdA MOBIHEALTH NEWS https:\/\/www.mobihealthnews.com\/news\/aws-new-accelerator-cohort-will-focus-health-equity-and-more-digital-health-briefs KIDSX https:\/\/www.kidsx.health\/aws-accelerator\/<\/p>","protected":false},"author":1,"featured_media":26713,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160,3396],"tags":[145],"class_list":["post-26711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-uso-de-plataformas-digitales","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/26711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=26711"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/26711\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/26713"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=26711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=26711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=26711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}