{"id":24431,"date":"2022-03-17T09:20:29","date_gmt":"2022-03-17T15:20:29","guid":{"rendered":"https:\/\/saluddigital.com\/?p=24431"},"modified":"2025-10-21T10:07:42","modified_gmt":"2025-10-21T16:07:42","slug":"la-importancia-de-mejorar-la-implementacion-y-evaluacion-de-la-inteligencia-artificial-en-salud","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/big-data\/la-importancia-de-mejorar-la-implementacion-y-evaluacion-de-la-inteligencia-artificial-en-salud\/","title":{"rendered":"The importance of improving the implementation and evaluation of Artificial Intelligence in health"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"24431\" class=\"elementor elementor-24431\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fc37f67 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6fc37f67\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23cb0378\" data-id=\"23cb0378\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37570eea elementor-widget elementor-widget-heading\" data-id=\"37570eea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Investigadores de la Facultad de Medicina de Harvard, publicaron un art\u00edculo que detalla algunos desaf\u00edos que persisten en la implementaci\u00f3n de herramientas de Inteligencia Artificial (IA) en salud.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3fb3d012 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3fb3d012\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c082657\" data-id=\"6c082657\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d5725cb elementor-widget elementor-widget-text-editor\" data-id=\"5d5725cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gracias a la IA, se han logrado diversos avances en la investigaci\u00f3n cl\u00ednica, y adem\u00e1s ha sido un asunto de especial inter\u00e9s entre la comunidad cient\u00edfica m\u00e9dica. No obstante, su verdadero alcance e impacto en los resultados de pacientes en entornos cl\u00ednicos no suele medirse correctamente.<\/p><p>Investigadores de la Facultad de Medicina de Harvard, publicaron la editorial \u201cCruzando el abismo del rendimiento del modelo al impacto cl\u00ednico: la necesidad de mejorar la implementaci\u00f3n y evaluaci\u00f3n de la IA\u201d, en npj Digital Medicine. El documento, muestra el limitado alcance de la IA en el campo cl\u00ednico. Los autores revisaron 65 ensayos controlados aleatorios de estudios de intervenciones cl\u00ednicas basadas en IA.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-876175d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"876175d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5319a56b\" data-id=\"5319a56b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bc7d088 elementor-widget elementor-widget-text-editor\" data-id=\"4bc7d088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Su an\u00e1lisis mostr\u00f3 que no hab\u00eda beneficio cl\u00ednico de usar herramientas de IA en comparaci\u00f3n con atenci\u00f3n est\u00e1ndar en casi el 40% de los estudios. Las herramientas de IA utilizadas fueron, modelos predictivos de aprendizaje profundo y aprendizaje autom\u00e1tico que sustitu\u00edan a las calculadoras de riesgo de estad\u00edsticas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-16e35ba6\" data-id=\"16e35ba6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-707a07ff elementor-widget elementor-widget-image\" data-id=\"707a07ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2022\/03\/03-22-21.jpg\" class=\"attachment-full size-full wp-image-24433\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2022\/03\/03-22-21.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2022\/03\/03-22-21-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2022\/03\/03-22-21-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2022\/03\/03-22-21-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2022\/03\/03-22-21-18x9.jpg 18w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1aaa46b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1aaa46b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6859f0bc\" data-id=\"6859f0bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-648bf29f elementor-widget elementor-widget-text-editor\" data-id=\"648bf29f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cLa adopci\u00f3n limitada por parte de los usuarios, debido a la falta de confianza del m\u00e9dico y la interpretabilidad del modelo, entre muchas otras razones, se ha citado durante mucho tiempo como una barrera clave para el impacto cl\u00ednico\u201d, explican los autores.<\/p><p>Los autores consideran una IA exitosa aquella que desencadena un flujo de trabajo personalizado, es decir que la predicci\u00f3n utilizando IA, debe mejorar la intervenci\u00f3n humana, para que tenga un impacto cl\u00ednico positivo. \u201cDebemos desarrollar m\u00e9todos para identificar sistem\u00e1ticamente la mejor intervenci\u00f3n posible para emparejar con una predicci\u00f3n precisa\u201d, explican en la editorial.<\/p><p>Otro aspecto importante para mejorar los beneficios cl\u00ednicos de la IA, es desarrollar nuevas formas para su evaluaci\u00f3n, que sean menos costosos y adem\u00e1s se realicen en menos tiempo. La evaluaci\u00f3n puede realizarse a trav\u00e9s de informaci\u00f3n en bases de datos, registros cl\u00ednicos electr\u00f3nicos, entre otros.<\/p><p>Por ejemplo, la Administraci\u00f3n de Medicamentos y Alimentos de Estados Unidos, utiliza datos reales para informar sobre decisiones regulatorias sobre medicamentes o dispositivos m\u00e9dicos.<\/p><p>\u201cLas aplicaciones ampliadas, las definiciones m\u00e1s amplias de beneficio cl\u00ednico, los nuevos m\u00e9todos de evaluaci\u00f3n y las intervenciones personalizadas son solo algunas de las muchas consideraciones posibles que pueden ayudar a cerrar la brecha entre el rendimiento predictivo <em>in silico<\/em> y la utilidad en el mundo real\u201d, concluyen los autores.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ac270ab elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3ac270ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ba8cb9d\" data-id=\"1ba8cb9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6edff2a7 elementor-widget elementor-widget-toggle\" data-id=\"6edff2a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1861\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1861\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1861\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1861\"><p><strong>NATURE<\/strong><\/p><p><a href=\"https:\/\/www.nature.com\/articles\/s41746-022-00572-2\">https:\/\/www.nature.com\/articles\/s41746-022-00572-2<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Investigadores de la Facultad de Medicina de Harvard, publicaron un art\u00edculo que detalla algunos desaf\u00edos que persisten en la implementaci\u00f3n de herramientas de Inteligencia Artificial (IA) en salud. Gracias a la IA, se han logrado diversos avances en la investigaci\u00f3n cl\u00ednica, y adem\u00e1s ha sido un asunto de especial inter\u00e9s entre la comunidad cient\u00edfica m\u00e9dica. No obstante, su verdadero alcance e impacto en los resultados de pacientes en entornos cl\u00ednicos no suele medirse correctamente. Investigadores de la Facultad de Medicina de Harvard, publicaron la editorial \u201cCruzando el abismo del rendimiento del modelo al impacto cl\u00ednico: la necesidad de mejorar la implementaci\u00f3n y evaluaci\u00f3n de la IA\u201d, en npj Digital Medicine. El documento, muestra el limitado alcance de la IA en el campo cl\u00ednico. Los autores revisaron 65 ensayos controlados aleatorios de estudios de intervenciones cl\u00ednicas basadas en IA. Su an\u00e1lisis mostr\u00f3 que no hab\u00eda beneficio cl\u00ednico de usar herramientas de IA en comparaci\u00f3n con atenci\u00f3n est\u00e1ndar en casi el 40% de los estudios. Las herramientas de IA utilizadas fueron, modelos predictivos de aprendizaje profundo y aprendizaje autom\u00e1tico que sustitu\u00edan a las calculadoras de riesgo de estad\u00edsticas. \u201cLa adopci\u00f3n limitada por parte de los usuarios, debido a la falta de confianza del m\u00e9dico y la interpretabilidad del modelo, entre muchas otras razones, se ha citado durante mucho tiempo como una barrera clave para el impacto cl\u00ednico\u201d, explican los autores. Los autores consideran una IA exitosa aquella que desencadena un flujo de trabajo personalizado, es decir que la predicci\u00f3n utilizando IA, debe mejorar la intervenci\u00f3n humana, para que tenga un impacto cl\u00ednico positivo. \u201cDebemos desarrollar m\u00e9todos para identificar sistem\u00e1ticamente la mejor intervenci\u00f3n posible para emparejar con una predicci\u00f3n precisa\u201d, explican en la editorial. Otro aspecto importante para mejorar los beneficios cl\u00ednicos de la IA, es desarrollar nuevas formas para su evaluaci\u00f3n, que sean menos costosos y adem\u00e1s se realicen en menos tiempo. La evaluaci\u00f3n puede realizarse a trav\u00e9s de informaci\u00f3n en bases de datos, registros cl\u00ednicos electr\u00f3nicos, entre otros. Por ejemplo, la Administraci\u00f3n de Medicamentos y Alimentos de Estados Unidos, utiliza datos reales para informar sobre decisiones regulatorias sobre medicamentes o dispositivos m\u00e9dicos. \u201cLas aplicaciones ampliadas, las definiciones m\u00e1s amplias de beneficio cl\u00ednico, los nuevos m\u00e9todos de evaluaci\u00f3n y las intervenciones personalizadas son solo algunas de las muchas consideraciones posibles que pueden ayudar a cerrar la brecha entre el rendimiento predictivo in silico y la utilidad en el mundo real\u201d, concluyen los autores. BIBLIOGRAF\u00cdA NATURE https:\/\/www.nature.com\/articles\/s41746-022-00572-2<\/p>","protected":false},"author":1,"featured_media":24433,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3399,156,3393,160,1418],"tags":[145],"class_list":["post-24431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ai-analitica","category-big-data","category-inteligencia-artificial-y-ciencia","category-noticias","category-resena-de-publicaciones-cientificas","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/24431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=24431"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/24431\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/24433"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=24431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=24431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=24431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}