{"id":14571,"date":"2021-05-04T09:39:46","date_gmt":"2021-05-04T14:39:46","guid":{"rendered":"https:\/\/saluddigital.com\/?p=14571"},"modified":"2025-10-21T12:48:01","modified_gmt":"2025-10-21T18:48:01","slug":"unam-ofrecio-mas-de-12-mil-teleconsultas-en-salud-mental-el-ultimo-ano","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/comunidades-conectadas\/unam-ofrecio-mas-de-12-mil-teleconsultas-en-salud-mental-el-ultimo-ano\/","title":{"rendered":"UNAM offered more than 12,000 mental health teleconsultations in the last year"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"14571\" class=\"elementor elementor-14571\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c4310d6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2c4310d6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10de2e6c\" data-id=\"10de2e6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e48b0b7 elementor-widget elementor-widget-heading\" data-id=\"2e48b0b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A year ago, the Mental Health Program of the Faculty of Medicine of the National Autonomous University of Mexico (UNAM) launched its psychiatric and psychological care teleconsultation program.  <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4164ce32 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4164ce32\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2cd2f4f\" data-id=\"2cd2f4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-749c69b4 elementor-widget elementor-widget-text-editor\" data-id=\"749c69b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Mental Health Program of the Faculty of Medicine of the UNAM began offering remote consultations for the university community in March 2020. According to the same institution in the first 12 months of adopting this modality, they have offered a total of 12,619 teleconsultations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7aaa4a90 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7aaa4a90\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-66e58eec\" data-id=\"66e58eec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f96222b elementor-widget elementor-widget-image\" data-id=\"3f96222b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2021\/05\/UNAM-ofrecio-mas-de-12-mil-teleconsultas-en-salud-mental-el-ultimo-ano.jpg\" class=\"attachment-full size-full wp-image-14572\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2021\/05\/UNAM-ofrecio-mas-de-12-mil-teleconsultas-en-salud-mental-el-ultimo-ano.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2021\/05\/UNAM-ofrecio-mas-de-12-mil-teleconsultas-en-salud-mental-el-ultimo-ano-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2021\/05\/UNAM-ofrecio-mas-de-12-mil-teleconsultas-en-salud-mental-el-ultimo-ano-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2021\/05\/UNAM-ofrecio-mas-de-12-mil-teleconsultas-en-salud-mental-el-ultimo-ano-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2021\/05\/UNAM-ofrecio-mas-de-12-mil-teleconsultas-en-salud-mental-el-ultimo-ano-16x8.jpg 16w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3a2bb91e\" data-id=\"3a2bb91e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1af7ff85 elementor-widget elementor-widget-text-editor\" data-id=\"1af7ff85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Of the consultations, 10,462 belonged to the Mental Health Clinic, 1,438 corresponded to the Comprehensive Addiction Care Clinic and 791 to the Gender Clinic.<\/p><p>The Department of Psychiatry and Mental Health (DPSM) reported that the most common problems treated through this modality are related to anxiety disorders, depression, domestic violence and drug abuse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dd7f4b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"dd7f4b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-468486e8\" data-id=\"468486e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fa70b7d elementor-widget elementor-widget-text-editor\" data-id=\"6fa70b7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cGiven the lockdown, one of the greatest needs has been mental health care, so suspending the service was not feasible and we set out to provide quality consultations,\u201d said Dr. Benjamin Guerrero L\u00f3pez, head of the DPSM and coordinator of the Mental Health Program Clinic.<\/p><p>Dr. Guerrero L\u00f3pez, detailed that, from March to August 2020, his department provided more than 1,500 continuous psychiatric consultations generally through telemedicine. However, the increase in requests made it necessary to redesign the project in August.<\/p><p>\u201cIt was in August when a new approach of normality was given to the consultations, for that reason the platform has been in constant improvement and adaptation,\u201d explained Jorge Camacho Morales, head of Development of the Department of Biomedical Informatics (DIB).<\/p><p>Learn more about this program and how to schedule an appointment by clicking on the following links: <a href=\"http:\/\/paginas.facmed.unam.mx\/deptos\/psi\/index.php\/2020\/09\/24\/dpsm\/\">http:\/\/paginas.facmed.unam.mx\/deptos\/psi\/index.php\/2020\/09\/24\/dpsm\/<\/a><\/p><p><a href=\"http:\/\/paginas.facmed.unam.mx\/deptos\/psi\/\">http:\/\/paginas.facmed.unam.mx\/deptos\/psi\/<\/a><\/p><p><a href=\"https:\/\/sistemasib.facmed.unam.mx\/saludMental\/\">https:\/\/sistemasib.facmed.unam.mx\/saludMental\/<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3b2dae elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"d3b2dae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35a1d508\" data-id=\"35a1d508\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f508d2e elementor-widget elementor-widget-toggle\" data-id=\"f508d2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2561\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2561\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2561\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2561\"><p><strong>THE DAY<\/strong><\/p><p><a href=\"https:\/\/www.jornada.com.mx\/notas\/2021\/04\/28\/sociedad\/brinda-unam-12-mil-691-teleconsultas-sobre-salud-mental-en-un-ano\/\">https:\/\/www.jornada.com.mx\/notas\/2021\/04\/28\/sociedad\/brinda-unam-12-mil-691-teleconsultas-sobre-salud-mental-en-un-ano\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Hace un a\u00f1o el Programa de Salud Mental de la Facultad de Medicina de la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM) puso en marcha su programa de teleconsultas en atenci\u00f3n psiqui\u00e1trica y psicol\u00f3gica. Programa de Salud Mental de la Facultad de Medicina de la UNAM comenz\u00f3 a ofrecer consultas distancia para la comunidad universitaria en marzo de 2020. Seg\u00fan la misma instituci\u00f3n en los primeros 12 meses de adoptar dicha modalidad, han ofrecido un total de 12 mil 619 teleconsultas. 10 mil 462 de las consultas pertenecieron a la Cl\u00ednica de Salud Mental, mil 438 correspondieron a la Cl\u00ednica Atenci\u00f3n Integral de las Adicciones y 791 correspondientes a la Cl\u00ednica de G\u00e9nero. El Departamento de Psiquiatr\u00eda y Salud Mental (DPSM), inform\u00f3 que los problemas m\u00e1s atendidos a trav\u00e9s de esta modalidad est\u00e1n relacionados con trastornos de ansiedad, depresi\u00f3n, violencia dom\u00e9stica y consumo de drogas. \u201cAnte el confinamiento, una de las mayores necesidades ha sido la atenci\u00f3n a la salud mental, por lo que suspender el servicio no era viable y nos propusimos brindar consultas de calidad\u201d, dijo el Dr. Benjam\u00edn Guerrero L\u00f3pez, jefe del DPSM y coordinador de la Cl\u00ednica del Programa de Salud Mental. El Dr. Guerrero L\u00f3pez, detall\u00f3 que, de marzo a agosto de 2020, en su departamento brindaron m\u00e1s de mil 500 consultas psiqui\u00e1tricas continuas generalmente a trav\u00e9s de telemedicina. Sin embargo, el aumento en las solicitudes oblig\u00f3 a redise\u00f1ar el proyecto en agosto. \u201cFue en agosto cuando se le dio un nuevo enfoque de normalidad a las consultas, por ese motivo la plataforma ha estado en mejora y adaptaci\u00f3n constante\u201d, explic\u00f3 Jorge Camacho Morales, responsable de Desarrollo del Departamento de Inform\u00e1tica Biom\u00e9dica (DIB). Conoce m\u00e1s sobre este programa y c\u00f3mo agendar una cita en los siguientes enlaces: http:\/\/paginas.facmed.unam.mx\/deptos\/psi\/index.php\/2020\/09\/24\/dpsm\/ http:\/\/paginas.facmed.unam.mx\/deptos\/psi\/ https:\/\/sistemasib.facmed.unam.mx\/saludMental\/ BIBLIOGRAF\u00cdA LA JORNADA https:\/\/www.jornada.com.mx\/notas\/2021\/04\/28\/sociedad\/brinda-unam-12-mil-691-teleconsultas-sobre-salud-mental-en-un-ano\/<\/p>","protected":false},"author":1,"featured_media":14572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154,3394,3396],"tags":[145],"class_list":["post-14571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidades-conectadas","category-redes-sociales","category-uso-de-plataformas-digitales","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/14571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=14571"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/14571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/14572"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=14571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=14571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=14571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}