{"id":12652,"date":"2021-03-01T10:52:34","date_gmt":"2021-03-01T16:52:34","guid":{"rendered":"https:\/\/saluddigital.com\/?p=12652"},"modified":"2025-10-21T13:00:40","modified_gmt":"2025-10-21T19:00:40","slug":"google-lanzo-una-nueva-herramienta-de-busqueda-para-la-organizacion-de-expedientes-medicos-electronicos","status":"publish","type":"post","link":"https:\/\/saluddigital.com\/en\/plataformas-digitales\/google-lanzo-una-nueva-herramienta-de-busqueda-para-la-organizacion-de-expedientes-medicos-electronicos\/","title":{"rendered":"Google launches new search tool for electronic health records organization"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"12652\" class=\"elementor elementor-12652\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a3f701f elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5a3f701f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1443d9bf\" data-id=\"1443d9bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0c859b elementor-widget elementor-widget-heading\" data-id=\"c0c859b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Google announced Care Studio, a tool for medical professionals to organize patients' electronic health records through a clinical search function.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-138e02ca elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"138e02ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79d19801\" data-id=\"79d19801\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cacb196 elementor-widget elementor-widget-text-editor\" data-id=\"2cacb196\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Google Health announced on February 23 the launch of Care Studio, a tool designed for the organization of complex health data, which also aims to help medical professionals spend less time organizing information and data. Google aims to solve the problem that medical professionals have when reviewing and navigating electronic health records (EHRs), as according to JAMA Network research, they spend half of their workday trying to organize information.<\/p><p>\"Care Studio leverages Google's expertise in organizing information to help clinicians find health record information faster,\" Google Health explains on the official Care Studio site. It further explains that the tool's clinical search function enables simple searches so that both medical and nursing staff can just type in the terms they are looking for and quickly find the information they require in an organized manner.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7651270e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7651270e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6698650b\" data-id=\"6698650b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1022571f elementor-widget elementor-widget-image\" data-id=\"1022571f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2021\/03\/Google-lanzo-una-nueva-herramienta-de-busqueda-para-la-organizacion-de-expedientes-medicos-electronicos.jpg\" class=\"attachment-full size-full wp-image-12653\" alt=\"\" srcset=\"https:\/\/saluddigital.com\/wp-content\/uploads\/2021\/03\/Google-lanzo-una-nueva-herramienta-de-busqueda-para-la-organizacion-de-expedientes-medicos-electronicos.jpg 1200w, https:\/\/saluddigital.com\/wp-content\/uploads\/2021\/03\/Google-lanzo-una-nueva-herramienta-de-busqueda-para-la-organizacion-de-expedientes-medicos-electronicos-660x347.jpg 660w, https:\/\/saluddigital.com\/wp-content\/uploads\/2021\/03\/Google-lanzo-una-nueva-herramienta-de-busqueda-para-la-organizacion-de-expedientes-medicos-electronicos-840x441.jpg 840w, https:\/\/saluddigital.com\/wp-content\/uploads\/2021\/03\/Google-lanzo-una-nueva-herramienta-de-busqueda-para-la-organizacion-de-expedientes-medicos-electronicos-768x403.jpg 768w, https:\/\/saluddigital.com\/wp-content\/uploads\/2021\/03\/Google-lanzo-una-nueva-herramienta-de-busqueda-para-la-organizacion-de-expedientes-medicos-electronicos-16x8.jpg 16w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-625bb42d\" data-id=\"625bb42d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16dbb6bb elementor-widget elementor-widget-text-editor\" data-id=\"16dbb6bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\"Our tools give clinicians a single, centralized view that automatically brings forward a patient\u2019s important information, including hospital visits, outpatient events, laboratory tests, medications, and treatment and progress notes. And the intuitive interface offers unique ways to visualize health data and trends in tables, graphs and other helpful formats.,\" explains Google Health.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2dda1c28 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2dda1c28\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d9744fd\" data-id=\"2d9744fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ab35fbe elementor-widget elementor-widget-text-editor\" data-id=\"2ab35fbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dr. Peter Clardy, a clinical specialist at Google Health, explained that through Care Studio, patient data, regardless of whether they belong to EHR from different health systems, will appear unified in searches. For example, lab results from different EHR will appear within a single record, and can be displayed through statistics and graphs with all the information collected on the patient.<\/p><p>Regarding privacy, Dr. Clardy explained that Care Studio complies with the necessary regulations and protects patients' personal data, including HIPAA (Health Insurance Portability and Accountability Act). \"We are excited about the opportunity to support more proactive care for physicians and their patients,\" he concluded.<\/p><p>\u00a0<\/p><p>Learn more at the following link: <a href=\"https:\/\/youtu.be\/71DVIWZnOho\">https:\/\/youtu.be\/71DVIWZnOho<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b981595 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1b981595\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f826075\" data-id=\"2f826075\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5336a704 elementor-widget elementor-widget-toggle\" data-id=\"5336a704\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1391\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1391\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> BIBLIOGRAPHY<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1391\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1391\"><p><strong>GOOGLE HEALTH\u00a0 <\/strong><\/p><p><a href=\"https:\/\/health.google\/for-clinicians\/care-studio\/\">https:\/\/health.google\/for-clinicians\/care-studio\/<\/a><\/p><p><strong>\u00a0<\/strong><\/p><p><strong>MEDICAL DEVICE NETWORK <\/strong><\/p><p><a href=\"https:\/\/www.medicaldevice-network.com\/news\/care-studio\/\">https:\/\/www.medicaldevice-network.com\/news\/care-studio\/<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Google anunci\u00f3 Care Studio, una herramienta para que profesionales m\u00e9dicos organicen los registros cl\u00ednicos electr\u00f3nicos de pacientes a trav\u00e9s de una funci\u00f3n de b\u00fasqueda cl\u00ednica. Google Health anunci\u00f3 el 23 de febrero el lanzamiento de Care Studio, una herramienta dise\u00f1ada para la organizaci\u00f3n de datos complejos sobre salud, que busca adem\u00e1s que los profesionales m\u00e9dicos pasen menos tiempo organizando la informaci\u00f3n y los datos. Google apunta a resolver el problema que tiene los profesionales m\u00e9dicos al revisar y navegar por los expedientes cl\u00ednicos electr\u00f3nicos (ECE), ya que seg\u00fan una investigaci\u00f3n de JAMA Network, pasan la mitad de su jornada laboral tratando de organizar la informaci\u00f3n. \u201cCare Studio aprovecha la experiencia de Google en la organizaci\u00f3n de informaci\u00f3n para ayudar a los m\u00e9dicos a encontrar informaci\u00f3n de registros m\u00e9dicos m\u00e1s r\u00e1pidamente\u201d, explica Google Health en el sitio oficial de Care Studio. Adem\u00e1s, explica que la funci\u00f3n de b\u00fasqueda cl\u00ednica de la herramienta permite b\u00fasquedas sencillas para que tanto el personal m\u00e9dico como de enfermer\u00eda solo escriban los t\u00e9rminos que buscan y encontraran r\u00e1pidamente la informaci\u00f3n que requieren de forma organizada. \u201cNuestras herramientas brindan a los m\u00e9dicos una vista \u00fanica y centralizada que presenta autom\u00e1ticamente la informaci\u00f3n importante del paciente, incluidas las visitas al hospital, eventos ambulatorios, pruebas de laboratorio, medicamentos y notas de tratamiento y progreso. Y la interfaz intuitiva ofrece formas \u00fanicas de visualizar datos y tendencias de salud en tablas, gr\u00e1ficos y otros formatos \u00fatiles\u201d, explica Google Health. El Dr. Peter Clardy especialista cl\u00ednico de Google Health explico que a trav\u00e9s de Care Studio, los datos de los pacientes sin importar si pertenecen a ECE de diferentes sistemas de salud, aparecer\u00e1n unificados en las b\u00fasquedas. Por ejemplo, los resultados de laboratorio de diferentes ECE aparecer\u00e1n dentro de un solo expediente, y podr\u00e1n ser mostrados a trav\u00e9s de estad\u00edsticas y graficas con toda la informaci\u00f3n recolectada sobre el paciente. Con respecto a la privacidad el Dr. Clardy explic\u00f3 que Care Studio cumple con las regulaciones necesaria y protegen los datos personales de los pacientes, incluida la HIPAA (Ley de Transferencia y Responsabilidad de Seguro M\u00e9dico). \u201cNos entusiasma la oportunidad de apoyar una atenci\u00f3n m\u00e1s proactiva para los m\u00e9dicos y sus pacientes,\u201d concluy\u00f3. \u00a0 Conoce m\u00e1s en el siguiente enlace: https:\/\/youtu.be\/71DVIWZnOho BIBLIOGRAF\u00cdA GOOGLE HEALTH\u00a0 https:\/\/health.google\/for-clinicians\/care-studio\/ \u00a0 MEDICAL DEVICE NETWORK https:\/\/www.medicaldevice-network.com\/news\/care-studio\/<\/p>","protected":false},"author":1,"featured_media":12653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154,153],"tags":[145],"class_list":["post-12652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidades-conectadas","category-plataformas-digitales","tag-noticias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/12652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/comments?post=12652"}],"version-history":[{"count":0,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/posts\/12652\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media\/12653"}],"wp:attachment":[{"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/media?parent=12652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/categories?post=12652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saluddigital.com\/en\/wp-json\/wp\/v2\/tags?post=12652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}